{"id":46851,"date":"2023-09-05T05:37:57","date_gmt":"2023-09-05T09:37:57","guid":{"rendered":"https:\/\/aladyr.net\/socios\/grupo-wasser-2\/"},"modified":"2023-09-05T05:37:57","modified_gmt":"2023-09-05T09:37:57","slug":"grupo-wasser-2","status":"publish","type":"socios","link":"https:\/\/aladyr.net\/pt-br\/s\u00f3cios\/grupo-wasser-2\/","title":{"rendered":"GRUPO WASSER"},"content":{"rendered":"","protected":false},"featured_media":39179,"template":"","tags":[],"class_list":["post-46851","socios","type-socios","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GRUPO WASSER - Aladyr<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aladyr.net\/pt-br\/s\u00f3cios\/grupo-wasser-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GRUPO WASSER - Aladyr\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aladyr.net\/pt-br\/s\u00f3cios\/grupo-wasser-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Aladyr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionaladyr\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@aladyr_asoc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/s\u00f3cios\\\/grupo-wasser-2\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/s\u00f3cios\\\/grupo-wasser-2\\\/\",\"name\":\"GRUPO WASSER - Aladyr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/s\u00f3cios\\\/grupo-wasser-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/s\u00f3cios\\\/grupo-wasser-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/grupo-wasser.png\",\"datePublished\":\"2023-09-05T09:37:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/s\u00f3cios\\\/grupo-wasser-2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/s\u00f3cios\\\/grupo-wasser-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/s\u00f3cios\\\/grupo-wasser-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/grupo-wasser.png\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/grupo-wasser.png\",\"width\":250,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/s\u00f3cios\\\/grupo-wasser-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Socios ALADYR\",\"item\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/s\u00f3cios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GRUPO WASSER\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/\",\"name\":\"Aladyr\",\"description\":\"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua\",\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#organization\",\"name\":\"Aladyr\",\"url\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"width\":600,\"height\":400,\"caption\":\"Aladyr\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/asociacionaladyr\\\/\",\"https:\\\/\\\/x.com\\\/aladyr_asoc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aladyr\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGIYolI-td4K6GiafV32rA\",\"https:\\\/\\\/www.instagram.com\\\/aladyr_asociacion\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GRUPO WASSER - Aladyr","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aladyr.net\/pt-br\/s\u00f3cios\/grupo-wasser-2\/","og_locale":"pt_BR","og_type":"article","og_title":"GRUPO WASSER - Aladyr","og_url":"https:\/\/aladyr.net\/pt-br\/s\u00f3cios\/grupo-wasser-2\/","og_site_name":"Aladyr","article_publisher":"https:\/\/www.facebook.com\/asociacionaladyr\/","og_image":[{"width":600,"height":400,"url":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@aladyr_asoc","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aladyr.net\/pt-br\/s\u00f3cios\/grupo-wasser-2\/","url":"https:\/\/aladyr.net\/pt-br\/s\u00f3cios\/grupo-wasser-2\/","name":"GRUPO WASSER - Aladyr","isPartOf":{"@id":"https:\/\/aladyr.net\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aladyr.net\/pt-br\/s\u00f3cios\/grupo-wasser-2\/#primaryimage"},"image":{"@id":"https:\/\/aladyr.net\/pt-br\/s\u00f3cios\/grupo-wasser-2\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2023\/09\/grupo-wasser.png","datePublished":"2023-09-05T09:37:57+00:00","breadcrumb":{"@id":"https:\/\/aladyr.net\/pt-br\/s\u00f3cios\/grupo-wasser-2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aladyr.net\/pt-br\/s\u00f3cios\/grupo-wasser-2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/aladyr.net\/pt-br\/s\u00f3cios\/grupo-wasser-2\/#primaryimage","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2023\/09\/grupo-wasser.png","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2023\/09\/grupo-wasser.png","width":250,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/aladyr.net\/pt-br\/s\u00f3cios\/grupo-wasser-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aladyr.net\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Socios ALADYR","item":"https:\/\/aladyr.net\/pt-br\/s\u00f3cios\/"},{"@type":"ListItem","position":3,"name":"GRUPO WASSER"}]},{"@type":"WebSite","@id":"https:\/\/aladyr.net\/pt-br\/#website","url":"https:\/\/aladyr.net\/pt-br\/","name":"Aladyr","description":"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua","publisher":{"@id":"https:\/\/aladyr.net\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aladyr.net\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/aladyr.net\/pt-br\/#organization","name":"Aladyr","url":"https:\/\/aladyr.net\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","width":600,"height":400,"caption":"Aladyr"},"image":{"@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/asociacionaladyr\/","https:\/\/x.com\/aladyr_asoc","https:\/\/www.linkedin.com\/company\/aladyr","https:\/\/www.youtube.com\/channel\/UCeGIYolI-td4K6GiafV32rA","https:\/\/www.instagram.com\/aladyr_asociacion\/"]}]}},"_links":{"self":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/socios\/46851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/socios"}],"about":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/types\/socios"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/media\/39179"}],"wp:attachment":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/media?parent=46851"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/tags?post=46851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}