{"id":40679,"date":"2024-03-07T17:30:09","date_gmt":"2024-03-07T21:30:09","guid":{"rendered":"https:\/\/aladyr.net\/?p=40679"},"modified":"2024-03-07T17:34:27","modified_gmt":"2024-03-07T21:34:27","slug":"water-positive-en-el-marco-de-la-race-to-resilience","status":"publish","type":"post","link":"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/","title":{"rendered":"&#8220;Water Positive en el Marco de la Race to Resilience&#8221;"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"975\" src=\"https:\/\/aladyr.net\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.46.07-AM-1024x975.jpeg\" alt=\"\" class=\"wp-image-40680\" srcset=\"https:\/\/aladyr.net\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.46.07-AM-1024x975.jpeg 1024w, https:\/\/aladyr.net\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.46.07-AM-300x286.jpeg 300w, https:\/\/aladyr.net\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.46.07-AM-768x731.jpeg 768w, https:\/\/aladyr.net\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.46.07-AM-100x95.jpeg 100w, https:\/\/aladyr.net\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.46.07-AM.jpeg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Expertos y l\u00edderes compartieron iniciativas y compromisos para combatir la falta de agua y avanzar hacia la seguridad h\u00eddrica. Se abordaron mecanismos de monitoreo y compensaci\u00f3n de la huella h\u00eddrica y formas de certificaci\u00f3n para productos y procesos<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prensa ALADYR- Con miras a la celebraci\u00f3n del D\u00eda Mundial del Agua el 22 de marzo, la Red Pacto Global Chile y el Water Positive Think Tank llevaron a cabo con \u00e9xito el webinar &#8220;Water Positive en el marco de la Race to Resilience&#8221;. Este evento tuvo lugar el jueves 7 de marzo de 2024, reuniendo a expertos y l\u00edderes en torno a la urgente tem\u00e1tica de la resiliencia h\u00eddrica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El webinar se centr\u00f3 en discutir la crisis global de estr\u00e9s h\u00eddrico y su conexi\u00f3n con el cambio clim\u00e1tico, coloc\u00e1ndola como un asunto de alta prioridad en la agenda de las empresas. Margarita Ducci, Directora Ejecutiva de la Red Pacto Global Chile, destac\u00f3 la importancia del compromiso empresarial en la consecuci\u00f3n del Objetivo de Desarrollo Sostenible 6, mientras que Camila Fern\u00e1ndez, L\u00edder de involucramiento para Am\u00e9rica Latina y el Caribe del equipo de High-Level Champions de la COP, enfatiz\u00f3 la necesidad de una gobernanza h\u00eddrica s\u00f3lida que integre al sector p\u00fablico y privado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cConocemos empresas interesadas en las iniciativas y certificaciones sobre eficiencia h\u00eddrica y para ello estamos capacit\u00e1ndolas con distintos programas\u201d complet\u00f3 la directora de Pacto Global Chile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Camila Fern\u00e1ndez detall\u00f3 que Chile es el pa\u00eds con mayor estr\u00e9s h\u00eddrico de la regi\u00f3n, pero que las organizaciones trabajan por el sue\u00f1o de convertirlo en el primero en alcanzar la seguridad h\u00eddrica y que este objetivo se posiciona como un horizonte claro gracias a la colaboraci\u00f3n con la industria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se expusieron estrategias centradas en la priorizaci\u00f3n de zonas con alto estr\u00e9s h\u00eddrico y en la consideraci\u00f3n de proyectos con alto impacto local, tales como la desalaci\u00f3n y el re\u00faso de agua, fundamentales en la escalabilidad de las soluciones a implementar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa de Water Resilience Coalition fue discutida como un esfuerzo colaborativo para abordar el estr\u00e9s h\u00eddrico. Paralelamente, los asistentes tuvieron la oportunidad de familiarizarse con ejemplos espec\u00edficos de la Water Positive Initiative, que busca fomentar una contribuci\u00f3n neta positiva a los recursos h\u00eddricos a nivel global, incentivando la adopci\u00f3n de tecnolog\u00edas para generar agua dulce a partir del mar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con la participaci\u00f3n de expertos como Alejandro Sturniolo, VP de Marketing y Sostenibilidad de H2O Innovations, y Antonella Maggioni, CEO de Agrow Analytics, se compartieron perspectivas valiosas sobre c\u00f3mo la industria puede asumir responsabilidades y crear un impacto positivo en el medio ambiente. Las discusiones tambi\u00e9n abordaron el papel crucial de las certificaciones, medidas de eficiencia h\u00eddrica en el \u00e1mbito corporativo y el monitoreo de las cuencas en las que operan las empresas y productores de materia prima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;El 90% de la huella h\u00eddrica global es resultado de la actividad industrial. Es una responsabilidad que recae directamente sobre nosotros, ya que esas industrias &#8211; sean mineras, farmac\u00e9uticas o agr\u00edcolas \u2013operan para satisfacer nuestras necesidades. La clave est\u00e1 en garantizar el suministro de agua a la poblaci\u00f3n mientras producimos para estos sectores. Nos comprometemos a generar m\u00e1s agua de la que consumimos en nuestros productos y servicios, asegurando una contribuci\u00f3n neta positiva al medio ambiente&#8221;, dijo Sturniolo respecto a la iniciativa Water Positive.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hicieron hincapi\u00e9 en la uni\u00f3n de esfuerzos entre corporaciones de renombre como Microsoft, Anglo American, Empresas Iansa y ABInBev, quienes junto a otras importantes entidades del sector privado, se comprometieron con un manejo sustentable y responsable del recurso h\u00eddrico bajo la premisa de ser Water Positive.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maggioni present\u00f3 un ejemplo de caso real donde se observa la gesti\u00f3n de la huella h\u00eddrica actual frente a la hist\u00f3rica, subrayando la importancia de la medici\u00f3n y la verificaci\u00f3n para el avance en la sostenibilidad h\u00eddrica. Asimismo, se discuti\u00f3 c\u00f3mo la certificaci\u00f3n de huellas h\u00eddricas, conforme a est\u00e1ndares internacionales como la ISO 14046:2014, es un paso vital para empresas que buscan la neutralidad y posterior positividad h\u00eddrica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCada vez vemos a m\u00e1s productores que quieren adquirir herramientas para medir su huella h\u00eddrica y avanzar en la eficiencia del recurso y que adem\u00e1s se informan sobre los mecanismos de compensaci\u00f3n y los beneficios que estos generan\u201d Agreg\u00f3 Maggioni.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento tambi\u00e9n destac\u00f3 las acciones para conectar con agricultores, demostrando c\u00f3mo la gesti\u00f3n del agua no solo es una cuesti\u00f3n de responsabilidad empresarial, sino tambi\u00e9n una oportunidad para generar un impacto positivo directo en comunidades y cuencas h\u00eddricas clave. La generaci\u00f3n de cr\u00e9ditos de agua y los esquemas de compensaci\u00f3n y reposici\u00f3n para empresas representan una oportunidad para el ahorro y uso eficiente del agua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Datos de premura<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Presentaron datos para contextualizar la urgencia del asunto: un 76% de la superficie de Chile se encuentra afectada por la sequ\u00eda y el suelo degradado con 101 comunas gravemente afectadas. En 2019, ciudades como Santiago, Valpara\u00edso y Curic\u00f3 registraron un d\u00e9ficit de precipitaciones de m\u00e1s del 70%. A nivel mundial, se resalt\u00f3 que el 25% de la poblaci\u00f3n global enfrenta un estr\u00e9s h\u00eddrico extremadamente alto cada a\u00f1o y se proyecta una alarmante escasez de 149 m\u00b3\/s para 2030.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento tambi\u00e9n sirvi\u00f3 para destacar casos de \u00e9xito, donde se mostr\u00f3 c\u00f3mo diversas compa\u00f1\u00edas han logrado ahorrar millones de metros c\u00fabicos de agua en los \u00faltimos a\u00f1os. La agenda de Water Positive resalt\u00f3 la asociaci\u00f3n con m\u00e1s de 35 socios para aumentar la resiliencia h\u00eddrica y puntualiz\u00f3 en la importancia del Pacto Seguridad H\u00eddrica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En respuesta a estos desaf\u00edos, se recalc\u00f3 la estrategia basada en tres pilares fundamentales: evitar y reducir impactos operacionales, colaboraci\u00f3n territorial para recuperar y restaurar las huellas h\u00eddricas y el uso sostenible del agua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los participantes enfatizaron que la colaboraci\u00f3n entre el sector p\u00fablico y privado es fundamental para abordar los desaf\u00edos de agua compartidos y para implementar soluciones efectivas. Este enfoque integrado es crucial para alcanzar el ODS 6 y asegurar la disponibilidad y gesti\u00f3n sostenible del agua y el saneamiento para todos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">ALADYR apoya estas iniciativas y es parte de los esfuerzos por la difusi\u00f3n de Water Positive en Latinoam\u00e9rica con ponencias en sus congresos, webinars y llamados de atenci\u00f3n a gremios e instituciones gubernamentales. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Concluyendo el evento, los l\u00edderes del Water Positive Think Tank y los representantes de las instituciones asistentes reafirmaron su compromiso con la gesti\u00f3n sostenible del agua, destacando los avances y los planes de acci\u00f3n futuros. El mensaje fue claro: la seguridad h\u00eddrica no solo es una preocupaci\u00f3n ambiental, sino una prioridad estrat\u00e9gica que requiere una respuesta urgente y coordinada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Expertos y l\u00edderes compartieron iniciativas y compromisos para combatir la falta de agua y avanzar hacia la seguridad h\u00eddrica. Se abordaron mecanismos de monitoreo y compensaci\u00f3n de la huella h\u00eddrica y formas de certificaci\u00f3n para productos y procesos<\/p>\n","protected":false},"author":2873,"featured_media":40680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-40679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Water Positive en el Marco de la Race to Resilience&quot; - Aladyr<\/title>\n<meta name=\"description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Water Positive en el Marco de la Race to Resilience&quot; - Aladyr\" \/>\n<meta property=\"og:description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/\" \/>\n<meta property=\"og:site_name\" content=\"Aladyr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionaladyr\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-07T21:30:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T21:34:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aladyr.net\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.46.07-AM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1028\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:site\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/water-positive-en-el-marco-de-la-race-to-resilience\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/water-positive-en-el-marco-de-la-race-to-resilience\\\/\"},\"author\":{\"name\":\"Diego Ortu\u00c3\u00b1o\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\"},\"headline\":\"&#8220;Water Positive en el Marco de la Race to Resilience&#8221;\",\"datePublished\":\"2024-03-07T21:30:09+00:00\",\"dateModified\":\"2024-03-07T21:34:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/water-positive-en-el-marco-de-la-race-to-resilience\\\/\"},\"wordCount\":1187,\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/water-positive-en-el-marco-de-la-race-to-resilience\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-07-at-10.46.07-AM.jpeg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/water-positive-en-el-marco-de-la-race-to-resilience\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/water-positive-en-el-marco-de-la-race-to-resilience\\\/\",\"name\":\"\\\"Water Positive en el Marco de la Race to Resilience\\\" - Aladyr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/water-positive-en-el-marco-de-la-race-to-resilience\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/water-positive-en-el-marco-de-la-race-to-resilience\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-07-at-10.46.07-AM.jpeg\",\"datePublished\":\"2024-03-07T21:30:09+00:00\",\"dateModified\":\"2024-03-07T21:34:27+00:00\",\"description\":\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/water-positive-en-el-marco-de-la-race-to-resilience\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/water-positive-en-el-marco-de-la-race-to-resilience\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/water-positive-en-el-marco-de-la-race-to-resilience\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-07-at-10.46.07-AM.jpeg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/WhatsApp-Image-2024-03-07-at-10.46.07-AM.jpeg\",\"width\":1080,\"height\":1028},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/water-positive-en-el-marco-de-la-race-to-resilience\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Water Positive en el Marco de la Race to Resilience&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/\",\"name\":\"Aladyr\",\"description\":\"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua\",\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#organization\",\"name\":\"Aladyr\",\"url\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"width\":600,\"height\":400,\"caption\":\"Aladyr\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/asociacionaladyr\\\/\",\"https:\\\/\\\/x.com\\\/aladyr_asoc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aladyr\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGIYolI-td4K6GiafV32rA\",\"https:\\\/\\\/www.instagram.com\\\/aladyr_asociacion\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\",\"name\":\"Diego Ortu\u00c3\u00b1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"caption\":\"Diego Ortu\u00c3\u00b1o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Water Positive en el Marco de la Race to Resilience\" - Aladyr","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/","og_locale":"pt_BR","og_type":"article","og_title":"\"Water Positive en el Marco de la Race to Resilience\" - Aladyr","og_description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","og_url":"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/","og_site_name":"Aladyr","article_publisher":"https:\/\/www.facebook.com\/asociacionaladyr\/","article_published_time":"2024-03-07T21:30:09+00:00","article_modified_time":"2024-03-07T21:34:27+00:00","og_image":[{"width":1080,"height":1028,"url":"https:\/\/aladyr.net\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.46.07-AM.jpeg","type":"image\/jpeg"}],"author":"Diego Ortu\u00c3\u00b1o","twitter_card":"summary_large_image","twitter_creator":"@aladyr_asoc","twitter_site":"@aladyr_asoc","twitter_misc":{"Escrito por":"Diego Ortu\u00c3\u00b1o","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/#article","isPartOf":{"@id":"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/"},"author":{"name":"Diego Ortu\u00c3\u00b1o","@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f"},"headline":"&#8220;Water Positive en el Marco de la Race to Resilience&#8221;","datePublished":"2024-03-07T21:30:09+00:00","dateModified":"2024-03-07T21:34:27+00:00","mainEntityOfPage":{"@id":"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/"},"wordCount":1187,"publisher":{"@id":"https:\/\/aladyr.net\/pt-br\/#organization"},"image":{"@id":"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.46.07-AM.jpeg","articleSection":["Noticias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/","url":"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/","name":"\"Water Positive en el Marco de la Race to Resilience\" - Aladyr","isPartOf":{"@id":"https:\/\/aladyr.net\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/#primaryimage"},"image":{"@id":"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.46.07-AM.jpeg","datePublished":"2024-03-07T21:30:09+00:00","dateModified":"2024-03-07T21:34:27+00:00","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","breadcrumb":{"@id":"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/#primaryimage","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.46.07-AM.jpeg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2024\/03\/WhatsApp-Image-2024-03-07-at-10.46.07-AM.jpeg","width":1080,"height":1028},{"@type":"BreadcrumbList","@id":"https:\/\/aladyr.net\/pt-br\/water-positive-en-el-marco-de-la-race-to-resilience\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aladyr.net\/pt-br\/"},{"@type":"ListItem","position":2,"name":"&#8220;Water Positive en el Marco de la Race to Resilience&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/aladyr.net\/pt-br\/#website","url":"https:\/\/aladyr.net\/pt-br\/","name":"Aladyr","description":"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua","publisher":{"@id":"https:\/\/aladyr.net\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aladyr.net\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/aladyr.net\/pt-br\/#organization","name":"Aladyr","url":"https:\/\/aladyr.net\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","width":600,"height":400,"caption":"Aladyr"},"image":{"@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/asociacionaladyr\/","https:\/\/x.com\/aladyr_asoc","https:\/\/www.linkedin.com\/company\/aladyr","https:\/\/www.youtube.com\/channel\/UCeGIYolI-td4K6GiafV32rA","https:\/\/www.instagram.com\/aladyr_asociacion\/"]},{"@type":"Person","@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f","name":"Diego Ortu\u00c3\u00b1o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","caption":"Diego Ortu\u00c3\u00b1o"}}]}},"_links":{"self":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/posts\/40679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/users\/2873"}],"replies":[{"embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/comments?post=40679"}],"version-history":[{"count":2,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/posts\/40679\/revisions"}],"predecessor-version":[{"id":40685,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/posts\/40679\/revisions\/40685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/media\/40680"}],"wp:attachment":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/media?parent=40679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/categories?post=40679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/tags?post=40679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}