{"id":20219,"date":"2021-01-26T14:05:32","date_gmt":"2021-01-26T18:05:32","guid":{"rendered":"https:\/\/aladyr.net\/?p=20219"},"modified":"2021-01-26T14:07:35","modified_gmt":"2021-01-26T18:07:35","slug":"desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water","status":"publish","type":"post","link":"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/","title":{"rendered":"Desalinizaci\u00f3n Solar Sin Bater\u00edas ni equipos auxiliares por Mascara Renewable Water"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/12\/osmosun-04-1-1024x577.jpg\" alt=\"La desalaci\u00f3n por \u00f3smosis inversa y la energ\u00eda fotovoltaica constituyen un matrimonio sostenible. La uni\u00f3n de estos dos ha sido probada en los confines m\u00e1s des\u00e9rticos del planeta para llevar agua potable en donde s\u00f3lo cuentan con agua de mar o pozos salobres. No obstante el \u00e9xito de la soluci\u00f3n; la relaci\u00f3n siempre se ha visto empa\u00f1ada por costos energ\u00e9ticos elevados o por el descarte pernicioso para el medio ambiente de las bater\u00edas de almacenamiento el\u00e9ctrico.\" class=\"wp-image-19863\" srcset=\"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/12\/osmosun-04-1-1024x577.jpg 1024w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/12\/osmosun-04-1-300x169.jpg 300w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/12\/osmosun-04-1-768x432.jpg 768w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/12\/osmosun-04-1-1536x865.jpg 1536w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/12\/osmosun-04-1-100x56.jpg 100w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/12\/osmosun-04-1-1200x676.jpg 1200w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/12\/osmosun-04-1.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>La desalaci\u00f3n por \u00f3smosis inversa y la energ\u00eda fotovoltaica constituyen un matrimonio sostenible. La uni\u00f3n de estos dos ha sido probada en los confines m\u00e1s des\u00e9rticos del planeta para llevar agua potable en donde s\u00f3lo cuentan con agua de mar o pozos salobres. No obstante el \u00e9xito de la soluci\u00f3n; la relaci\u00f3n siempre se ha visto empa\u00f1ada por costos energ\u00e9ticos elevados o por el descarte pernicioso para el medio ambiente de las bater\u00edas de almacenamiento el\u00e9ctrico.<br><br>Prescindir de las bater\u00edas no parec\u00eda posible porque las membranas de \u00f3smosis inversa requieren una potencia constante y las celdas fotovoltaicas est\u00e1n a merced de las intermitencias ocasionadas por las condiciones meteorol\u00f3gicas. Es aqu\u00ed donde entra en escena Mascara, una empresa socia ALADYR que remonta sus or\u00edgenes a una villa situada en la cordillera Atlas de Argelia &#8211; \u00c1frica, cuyo suministro de agua proveniente de pozos era apenas potable debido a su salobridad.<br><br>La propuesta de los fundadores de Mascara (nombre de aquella villa argelina) para que la desalaci\u00f3n por energ\u00eda solar fuese m\u00e1s asequible y sostenible fue OSMOSUN\u00ae, una tecnolog\u00eda patentada capaz de funcionar sin bater\u00edas y producir un caudal potable de hasta 600 metros c\u00fabicos diarios.<br><br>\u00bfC\u00f3mo funciona la desalaci\u00f3n por \u00f3smosis inversa y energ\u00eda solar sin bater\u00edas? \u00bfC\u00f3mo es posible? Y \u00bfQu\u00e9 beneficios trae? Para dar respuesta a esto y m\u00e1s M\u00e9lanie Ducros, gerente de proyectos de Mascara, dictar\u00e1 el webinar ALADYR este 04 de febrero, en compa\u00f1\u00eda de C\u00e9dric Plot, desarrollador de negocios.<br><br>El evento ser\u00e1 de participaci\u00f3n libre y se tratar\u00e1n conceptos como la alimentaci\u00f3n solar directa, sistema de \u00f3smosis inversa flexible y procesos inteligentes a partir de casos de \u00e9xito en Cabo Verde, Isla Bora Bora y Om\u00e1n, s\u00f3lo por mencionar algunos en el repertorio de soluciones de la empresa que incluye desalaci\u00f3n de agua de mar, de pozos salobres y plantas port\u00e1tiles en contenedores para casos de emergencia.<br>&nbsp;\u00ad\u00ad\u00ad\u00ad\u00ad<\/td><\/tr><tr><td>\u00ad\u00ad<strong>Sobre la expositora principal<\/strong><br><strong>M\u00e9lanie Ducros, Gerente de Proyectos:\u00a0<\/strong>Ingeniera especializada en las \u00e1reas de Energ\u00edas Renovables y Acceso al Agua Dulce. Trabaj\u00f3 con la Agencia Francesa de Desarrollo (AFD), la Uni\u00f3n Europea, el Banco Mundial y las Naciones Unidad en temas relacionados. Particip\u00f3 en el mayor proyecto de planta h\u00edbrida solar de \u00c1frica Subsahariana y en un proyecto innovador de colaboraci\u00f3n p\u00fablico-privada en la electrificaci\u00f3n y el acceso al agua dulce en zonas rurales en Mauritania. M\u00e9lanie formo tambi\u00e9n parte de proyectos de energ\u00eda mareomotriz con una Start-Up neerlandesa y un centro de investigaci\u00f3n brit\u00e1nico. Actualmente M\u00e9lanie es jefe de proyecto en Mascara y gestiona proyectos con multinacionales franceses, el ej\u00e9rcito franc\u00e9s y otros socios y clientes de Mascara especialmente en Australia, Chile y Europa.<br><br>Link de inscripci\u00f3n en el webinar: <a href=\"https:\/\/aladyr.net\/webinars\/desalinizacion-solar-sin-baterias-2\/\" data-type=\"URL\" data-id=\"https:\/\/aladyr.net\/webinars\/desalinizacion-solar-sin-baterias-2\/\">Osmosun<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La desalaci\u00f3n por \u00f3smosis inversa y la energ\u00eda fotovoltaica constituyen un matrimonio sostenible. La uni\u00f3n de estos dos ha sido probada en los confines m\u00e1s des\u00e9rticos del planeta para llevar agua potable en donde s\u00f3lo cuentan con agua de mar o pozos salobres. No obstante el \u00e9xito de la soluci\u00f3n; la relaci\u00f3n siempre se ha visto empa\u00f1ada por costos energ\u00e9ticos &#8230;<\/p>\n","protected":false},"author":2873,"featured_media":19863,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-20219","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Desalinizaci\u00f3n Solar Sin Bater\u00edas ni equipos auxiliares por Mascara Renewable Water - Aladyr<\/title>\n<meta name=\"description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desalinizaci\u00f3n Solar Sin Bater\u00edas ni equipos auxiliares por Mascara Renewable Water - Aladyr\" \/>\n<meta property=\"og:description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/\" \/>\n<meta property=\"og:site_name\" content=\"Aladyr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionaladyr\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-26T18:05:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-26T18:07:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/12\/osmosun-04-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1081\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:site\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\\\/\"},\"author\":{\"name\":\"Diego Ortu\u00c3\u00b1o\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\"},\"headline\":\"Desalinizaci\u00f3n Solar Sin Bater\u00edas ni equipos auxiliares por Mascara Renewable Water\",\"datePublished\":\"2021-01-26T18:05:32+00:00\",\"dateModified\":\"2021-01-26T18:07:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\\\/\"},\"wordCount\":511,\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/osmosun-04-1.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\\\/\",\"name\":\"Desalinizaci\u00f3n Solar Sin Bater\u00edas ni equipos auxiliares por Mascara Renewable Water - Aladyr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/osmosun-04-1.jpg\",\"datePublished\":\"2021-01-26T18:05:32+00:00\",\"dateModified\":\"2021-01-26T18:07:35+00:00\",\"description\":\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/osmosun-04-1.jpg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/osmosun-04-1.jpg\",\"width\":1920,\"height\":1081},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desalinizaci\u00f3n Solar Sin Bater\u00edas ni equipos auxiliares por Mascara Renewable Water\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/\",\"name\":\"Aladyr\",\"description\":\"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua\",\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#organization\",\"name\":\"Aladyr\",\"url\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"width\":600,\"height\":400,\"caption\":\"Aladyr\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/asociacionaladyr\\\/\",\"https:\\\/\\\/x.com\\\/aladyr_asoc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aladyr\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGIYolI-td4K6GiafV32rA\",\"https:\\\/\\\/www.instagram.com\\\/aladyr_asociacion\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\",\"name\":\"Diego Ortu\u00c3\u00b1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"caption\":\"Diego Ortu\u00c3\u00b1o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desalinizaci\u00f3n Solar Sin Bater\u00edas ni equipos auxiliares por Mascara Renewable Water - Aladyr","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/","og_locale":"pt_BR","og_type":"article","og_title":"Desalinizaci\u00f3n Solar Sin Bater\u00edas ni equipos auxiliares por Mascara Renewable Water - Aladyr","og_description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","og_url":"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/","og_site_name":"Aladyr","article_publisher":"https:\/\/www.facebook.com\/asociacionaladyr\/","article_published_time":"2021-01-26T18:05:32+00:00","article_modified_time":"2021-01-26T18:07:35+00:00","og_image":[{"width":1920,"height":1081,"url":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/12\/osmosun-04-1.jpg","type":"image\/jpeg"}],"author":"Diego Ortu\u00c3\u00b1o","twitter_card":"summary_large_image","twitter_creator":"@aladyr_asoc","twitter_site":"@aladyr_asoc","twitter_misc":{"Escrito por":"Diego Ortu\u00c3\u00b1o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/#article","isPartOf":{"@id":"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/"},"author":{"name":"Diego Ortu\u00c3\u00b1o","@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f"},"headline":"Desalinizaci\u00f3n Solar Sin Bater\u00edas ni equipos auxiliares por Mascara Renewable Water","datePublished":"2021-01-26T18:05:32+00:00","dateModified":"2021-01-26T18:07:35+00:00","mainEntityOfPage":{"@id":"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/"},"wordCount":511,"publisher":{"@id":"https:\/\/aladyr.net\/pt-br\/#organization"},"image":{"@id":"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/12\/osmosun-04-1.jpg","articleSection":["Noticias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/","url":"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/","name":"Desalinizaci\u00f3n Solar Sin Bater\u00edas ni equipos auxiliares por Mascara Renewable Water - Aladyr","isPartOf":{"@id":"https:\/\/aladyr.net\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/#primaryimage"},"image":{"@id":"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/12\/osmosun-04-1.jpg","datePublished":"2021-01-26T18:05:32+00:00","dateModified":"2021-01-26T18:07:35+00:00","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","breadcrumb":{"@id":"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/#primaryimage","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/12\/osmosun-04-1.jpg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/12\/osmosun-04-1.jpg","width":1920,"height":1081},{"@type":"BreadcrumbList","@id":"https:\/\/aladyr.net\/pt-br\/desalinizacion-solar-sin-baterias-ni-equipos-auxiliares-por-mascara-renewable-water\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aladyr.net\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Desalinizaci\u00f3n Solar Sin Bater\u00edas ni equipos auxiliares por Mascara Renewable Water"}]},{"@type":"WebSite","@id":"https:\/\/aladyr.net\/pt-br\/#website","url":"https:\/\/aladyr.net\/pt-br\/","name":"Aladyr","description":"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua","publisher":{"@id":"https:\/\/aladyr.net\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aladyr.net\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/aladyr.net\/pt-br\/#organization","name":"Aladyr","url":"https:\/\/aladyr.net\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","width":600,"height":400,"caption":"Aladyr"},"image":{"@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/asociacionaladyr\/","https:\/\/x.com\/aladyr_asoc","https:\/\/www.linkedin.com\/company\/aladyr","https:\/\/www.youtube.com\/channel\/UCeGIYolI-td4K6GiafV32rA","https:\/\/www.instagram.com\/aladyr_asociacion\/"]},{"@type":"Person","@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f","name":"Diego Ortu\u00c3\u00b1o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","caption":"Diego Ortu\u00c3\u00b1o"}}]}},"_links":{"self":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/posts\/20219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/users\/2873"}],"replies":[{"embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/comments?post=20219"}],"version-history":[{"count":0,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/posts\/20219\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/media\/19863"}],"wp:attachment":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/media?parent=20219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/categories?post=20219"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/tags?post=20219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}