{"id":16400,"date":"2020-09-21T16:02:57","date_gmt":"2020-09-21T20:02:57","guid":{"rendered":"https:\/\/aladyr.net\/?p=16400"},"modified":"2020-09-21T16:05:41","modified_gmt":"2020-09-21T20:05:41","slug":"colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia","status":"publish","type":"post","link":"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/","title":{"rendered":"Colombia: Gobierno invertir\u00e1 $1,7 billones en 158 obras de agua potable en Colombia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Estos proyectos&nbsp;generar\u00e1n m\u00e1s de 11.000 empleos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/www.laopinion.com.co\/sites\/default\/files\/styles\/640x370\/public\/2020\/08\/28\/imagen\/proyectos.jpg\" alt=\"Colprensa\" title=\"Ministro de Vivienda, Jonathan Malag\u00f3n. \" \/><figcaption>Ministro de Vivienda, Jonathan Malag\u00f3n.\/ Foto:Colprensa<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de la Rep\u00fablica, Iv\u00e1n Duque, anunci\u00f3 este jueves la inversi\u00f3n de m\u00e1s de 1,7 billones de pesos a trav\u00e9s de 158 obras que generar\u00e1n m\u00e1s de 11.000 empleos y mejorar\u00e1n la prestaci\u00f3n de estos servicios a cerca de 5 millones de colombianos en 132 municipios de 29 departamentos del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El mandatario explic\u00f3 que estos 158 proyectos ser\u00e1n realidad en diferentes etapas, \u201cunos en los pr\u00f3ximos d\u00edas, otros en las pr\u00f3ximas semanas,<\/strong>&nbsp;otros en los pr\u00f3ximos meses, pero sobre todo quedar\u00e1 el pa\u00eds con una continuidad de proyectos que van a cerrar la brecha de acceso al preciado liquido\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ministro de Vivienda, Jonathan Malag\u00f3n, inform\u00f3 que de las obras anunciadas por el presidente Duque, 20 se ponen en marcha ahora con una inversi\u00f3n de 139.300 millones de pesos. De ellos, 11 se realizar\u00e1n en los departamentos de Antioquia, Boyac\u00e1, C\u00f3rdoba, Cundinamarca, Huila, Magdalena, Quind\u00edo, Risaralda, Sucre y Valle del Cauca, beneficiando a 174.000 personas en once municipios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Malag\u00f3n se\u00f1al\u00f3 que otros nueve proyectos encienden la maquinaria en siete municipios PDET de Antioquia, Caquet\u00e1, Cesar, Choc\u00f3, C\u00f3rdoba y Putumayo,&nbsp;<\/strong>beneficiando a 53.000 personas. \u201cEn el Compromiso por Colombia no solamente queremos recuperar el ritmo de crecimiento que ten\u00edamos antes de la pandemia sino que queremos un pa\u00eds mejor al que ten\u00edamos seis meses atr\u00e1s\u201d, expres\u00f3.<\/p>\n\n\n\n<pre class=\"wp-block-preformatted\"><strong>Los primeros 20 proyectos son: <\/strong>\n\n- Villa de Leyva, Boyac\u00e1: construcci\u00f3n primera etapa plan maestro de alcantarillado. Inversi\u00f3n: $1.777 millones.\n\n- Monter\u00eda, C\u00f3rdoba: optimizaci\u00f3n del sistema de acueducto en la zona rural El Tapao y Sabanal. Inversi\u00f3n $6.230 millones. \n\n- El Banco, Magdalena: actualizaci\u00f3n de los estudios, dise\u00f1os, construcci\u00f3n y puesta en funcionamiento del sistema de alcantarillado del corregimiento de Bel\u00e9n. Inversi\u00f3n: $2.896 millones. \n\n- La Virginia, Risaralda: construcci\u00f3n fase III l\u00ednea de conducci\u00f3n acueducto urbano. Inversi\u00f3n: $3.940 millones. \n\n- Sincelejo, Sucre: extensi\u00f3n de redes de acueducto para el suministro de agua potable de Gallera. Inversi\u00f3n: $3.028 millones. \n\n- Palmira, Valle: abastecimiento de agua potable para los corregimientos de La Herradura, Obando y Matapalo. Inversi\u00f3n: $4.881 millones. \n\n- Guacar\u00ed, Valle: optimizaci\u00f3n de redes de distribuci\u00f3n acueducto corregimiento de Guabitas. Inversi\u00f3n$3.149 millones. \n\n- Armenia, Quind\u00edo: optimizaci\u00f3n del alcantarillado barrios La Clarita, La Isabela, Zuldemaida y Sim\u00f3n Bol\u00edvar. Inversi\u00f3n: $3.511 millones. \n\n- Pitalito, Huila: construcci\u00f3n de colectores del sistema de alcantarillado pluvial en la Comuna 1. Inversi\u00f3n de $2.905 millones. \n\n- G\u00f3mez Plata, Antioquia: construcci\u00f3n de redes de alcantarillado en los barrios Camell\u00f3n, Obrero, Lourdes y los sectores El Colegio y la carrera 51. Inversi\u00f3n $6.167 millones.\n\n- San Juan de Rioseco, Cundinamarca: construcci\u00f3n planta de tratamiento de residuos s\u00f3lidos org\u00e1nicos. Inversi\u00f3n $1.825 millones. \n\n- Valle del Guamuez, Putumayo: construcci\u00f3n del sistema de acueducto regional fase II. Inversi\u00f3n $54.562 millones de OCAD Paz.\n\n- Condot\u00f3, Choc\u00f3: optimizaci\u00f3n del sistema de acueducto y alcantarillado de los corregimientos La Hilaria, Jigualito, Opogod\u00f3, La Planta, Soledad de Tajuato y Consuelo de Andrapeda. Inversi\u00f3n: $ 9.985 millones OCAD Paz. \n\n- Chigorod\u00f3, Antioquia: construcci\u00f3n de acueducto en la comunidad ind\u00edgena Saud\u00f3. Inversi\u00f3n: $2.274 OCAD Paz. \n\n- Chigorod\u00f3, Antioquia: construcci\u00f3n de acueducto en la vereda Champitas. Inversi\u00f3n: $3.110 millones OCAD Paz. \n\n- Chigorod\u00f3, Antioquia: construcci\u00f3n de acueducto en la comunidad ind\u00edgena Dojura. Inversi\u00f3n: $2.362 millones OCAD Paz. \n\n- Montel\u00edbano, C\u00f3rdoba: construcci\u00f3n de unidades sanitarias en zona rural. Inversi\u00f3n $9.909 OCAD Paz. \n\n- Pueblo Bello, Cesar: optimizaci\u00f3n del sistema de acueducto y construcci\u00f3n del sistema de alcantarillado sanitario para el corregimiento de Nuevo Col\u00f3n. Inversi\u00f3n: $6.074 millones OCAD Paz. \n\n- El Bagre, Antioquia: construcci\u00f3n redes de acueducto del corregimiento Puerto Claver. Inversi\u00f3n: $7.189 millones OCAD Paz. \n\n- Solano, Caquet\u00e1: construcci\u00f3n alcantarillado sanitario y sistema de tratamiento de las aguas residuales para la inspecci\u00f3n de Campoalegre. Inversi\u00f3n: $3.264 millones OCAD Paz.\n<\/pre>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente:<a href=\"https:\/\/www.laopinion.com.co\/colombia\/gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia-201770\" target=\"_blank\" rel=\"noreferrer noopener\"> https:\/\/www.laopinion.com.co\/colombia\/gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia-201770<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Rep\u00fablica de Colombia, Iv\u00e1n Duque, anunci\u00f3 este jueves la inversi\u00f3n de m\u00e1s de 1,7 billones de pesos a trav\u00e9s de 158 obras que generar\u00e1n m\u00e1s de 11.000 empleos y mejorar\u00e1n la prestaci\u00f3n de estos servicios a cerca de 5 millones de colombianos en 132 municipios de 29 departamentos del pa\u00eds.<\/p>\n","protected":false},"author":2873,"featured_media":16402,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-16400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colombia: Gobierno invertir\u00e1 $1,7 billones en 158 obras de agua potable en Colombia - Aladyr<\/title>\n<meta name=\"description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colombia: Gobierno invertir\u00e1 $1,7 billones en 158 obras de agua potable en Colombia - Aladyr\" \/>\n<meta property=\"og:description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/\" \/>\n<meta property=\"og:site_name\" content=\"Aladyr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionaladyr\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-21T20:02:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-21T20:05:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/09\/ministro-de-vivienda-colombia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"370\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:site\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\\\/\"},\"author\":{\"name\":\"Diego Ortu\u00c3\u00b1o\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\"},\"headline\":\"Colombia: Gobierno invertir\u00e1 $1,7 billones en 158 obras de agua potable en Colombia\",\"datePublished\":\"2020-09-21T20:02:57+00:00\",\"dateModified\":\"2020-09-21T20:05:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\\\/\"},\"wordCount\":273,\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/ministro-de-vivienda-colombia.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\\\/\",\"name\":\"Colombia: Gobierno invertir\u00e1 $1,7 billones en 158 obras de agua potable en Colombia - Aladyr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/ministro-de-vivienda-colombia.jpg\",\"datePublished\":\"2020-09-21T20:02:57+00:00\",\"dateModified\":\"2020-09-21T20:05:41+00:00\",\"description\":\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/ministro-de-vivienda-colombia.jpg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/ministro-de-vivienda-colombia.jpg\",\"width\":640,\"height\":370},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colombia: Gobierno invertir\u00e1 $1,7 billones en 158 obras de agua potable en Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/\",\"name\":\"Aladyr\",\"description\":\"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua\",\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#organization\",\"name\":\"Aladyr\",\"url\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"width\":600,\"height\":400,\"caption\":\"Aladyr\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/asociacionaladyr\\\/\",\"https:\\\/\\\/x.com\\\/aladyr_asoc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aladyr\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGIYolI-td4K6GiafV32rA\",\"https:\\\/\\\/www.instagram.com\\\/aladyr_asociacion\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\",\"name\":\"Diego Ortu\u00c3\u00b1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"caption\":\"Diego Ortu\u00c3\u00b1o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colombia: Gobierno invertir\u00e1 $1,7 billones en 158 obras de agua potable en Colombia - Aladyr","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/","og_locale":"pt_BR","og_type":"article","og_title":"Colombia: Gobierno invertir\u00e1 $1,7 billones en 158 obras de agua potable en Colombia - Aladyr","og_description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","og_url":"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/","og_site_name":"Aladyr","article_publisher":"https:\/\/www.facebook.com\/asociacionaladyr\/","article_published_time":"2020-09-21T20:02:57+00:00","article_modified_time":"2020-09-21T20:05:41+00:00","og_image":[{"width":640,"height":370,"url":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/09\/ministro-de-vivienda-colombia.jpg","type":"image\/jpeg"}],"author":"Diego Ortu\u00c3\u00b1o","twitter_card":"summary_large_image","twitter_creator":"@aladyr_asoc","twitter_site":"@aladyr_asoc","twitter_misc":{"Escrito por":"Diego Ortu\u00c3\u00b1o","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/#article","isPartOf":{"@id":"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/"},"author":{"name":"Diego Ortu\u00c3\u00b1o","@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f"},"headline":"Colombia: Gobierno invertir\u00e1 $1,7 billones en 158 obras de agua potable en Colombia","datePublished":"2020-09-21T20:02:57+00:00","dateModified":"2020-09-21T20:05:41+00:00","mainEntityOfPage":{"@id":"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/"},"wordCount":273,"publisher":{"@id":"https:\/\/aladyr.net\/pt-br\/#organization"},"image":{"@id":"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/09\/ministro-de-vivienda-colombia.jpg","articleSection":["Noticias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/","url":"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/","name":"Colombia: Gobierno invertir\u00e1 $1,7 billones en 158 obras de agua potable en Colombia - Aladyr","isPartOf":{"@id":"https:\/\/aladyr.net\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/#primaryimage"},"image":{"@id":"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/09\/ministro-de-vivienda-colombia.jpg","datePublished":"2020-09-21T20:02:57+00:00","dateModified":"2020-09-21T20:05:41+00:00","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","breadcrumb":{"@id":"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/#primaryimage","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/09\/ministro-de-vivienda-colombia.jpg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/09\/ministro-de-vivienda-colombia.jpg","width":640,"height":370},{"@type":"BreadcrumbList","@id":"https:\/\/aladyr.net\/pt-br\/colombia-gobierno-invertira-17-billones-en-158-obras-de-agua-potable-en-colombia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aladyr.net\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Colombia: Gobierno invertir\u00e1 $1,7 billones en 158 obras de agua potable en Colombia"}]},{"@type":"WebSite","@id":"https:\/\/aladyr.net\/pt-br\/#website","url":"https:\/\/aladyr.net\/pt-br\/","name":"Aladyr","description":"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua","publisher":{"@id":"https:\/\/aladyr.net\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aladyr.net\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/aladyr.net\/pt-br\/#organization","name":"Aladyr","url":"https:\/\/aladyr.net\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","width":600,"height":400,"caption":"Aladyr"},"image":{"@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/asociacionaladyr\/","https:\/\/x.com\/aladyr_asoc","https:\/\/www.linkedin.com\/company\/aladyr","https:\/\/www.youtube.com\/channel\/UCeGIYolI-td4K6GiafV32rA","https:\/\/www.instagram.com\/aladyr_asociacion\/"]},{"@type":"Person","@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f","name":"Diego Ortu\u00c3\u00b1o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","caption":"Diego Ortu\u00c3\u00b1o"}}]}},"_links":{"self":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/posts\/16400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/users\/2873"}],"replies":[{"embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/comments?post=16400"}],"version-history":[{"count":0,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/posts\/16400\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/media\/16402"}],"wp:attachment":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/media?parent=16400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/categories?post=16400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/tags?post=16400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}