{"id":14960,"date":"2020-07-31T09:40:28","date_gmt":"2020-07-31T13:40:28","guid":{"rendered":"https:\/\/aladyr.net\/?p=14960"},"modified":"2020-07-31T09:41:53","modified_gmt":"2020-07-31T13:41:53","slug":"falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu","status":"publish","type":"post","link":"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/","title":{"rendered":"Falta de agua y saneamiento provoca tragedias humanas: ONU"},"content":{"rendered":"\n<h4 class=\"has-text-align-center wp-block-heading\"><strong>La ONU reconoci\u00f3 expl\u00edcitamente hace diez a\u00f1os el agua y el saneamiento como derechos humanos; sin embargo, miles de millones de personas carecen todav\u00eda de acceso a esos servicios b\u00e1sicos para su bienestar y su salud, lament\u00f3 el relator especial sobre esas garant\u00edas fundamentales.<\/strong><\/h4>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"798\" height=\"460\" src=\"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/07\/Saneamiento_Agua_ONU.jpg\" alt=\"\" class=\"wp-image-14961\" srcset=\"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/07\/Saneamiento_Agua_ONU.jpg 798w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/07\/Saneamiento_Agua_ONU-300x173.jpg 300w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/07\/Saneamiento_Agua_ONU-768x443.jpg 768w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/07\/Saneamiento_Agua_ONU-260x150.jpg 260w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/07\/Saneamiento_Agua_ONU-100x58.jpg 100w\" sizes=\"auto, (max-width: 798px) 100vw, 798px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En un comunicado, L\u00e9o Heller asever\u00f3 que la pandemia \u201cnos ha ense\u00f1ado que dejar atr\u00e1s a las personas que m\u00e1s necesitan los servicios de agua y de saneamiento puede conducir a una tragedia humanitaria\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 que en la pr\u00f3xima d\u00e9cada debe ser prioritario lograr que toda la poblaci\u00f3n cuente con esos servicios para \u201cconstruir sociedades justas y humanas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Heller record\u00f3 que el 28 de julio de 2010 la Asamblea General de las Naciones Unidas adopt\u00f3 una resoluci\u00f3n en la que todos los Estados miembros de la Organizaci\u00f3n se comprometieron a garantizar el acceso de todas las personas al agua y al saneamiento. Ese compromiso se reforz\u00f3 en la Agenda 2030, cuyos Objetivos de Desarrollo Sostenible buscan acabar con la pobreza, proteger el planeta y mejorar las vidas y las perspectivas futuras de toda la gente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El experto reconoci\u00f3 que la resoluci\u00f3n fue un buen punto de inicio y ha inspirado iniciativas y avances importantes, aunque a un ritmo lento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>M\u00e1s de la mitad de la poblaci\u00f3n sin acceso a saneamiento<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El relator especial dijo que los pa\u00edses no parecen estar listos para lograr los objetivos relativos al agua, el saneamiento y la higiene para 2030. Una de cada tres personas sigue sin poder acceder al agua potable y m\u00e1s de la mitad de la poblaci\u00f3n mundial carece de acceso a un saneamiento seguro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unos tres mil millones de personas no disponen de instalaciones b\u00e1sicas para el lavado de manos con jab\u00f3n y agua, y m\u00e1s de 673 millones de personas todav\u00eda practican la defecaci\u00f3n al aire libre. Esta situaci\u00f3n inaceptable causa 432,000 muertes debidas a la diarrea cada a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos compromisos de la Agenda 2030 son un incentivo para que nadie se quede atr\u00e1s, pero esto no ser\u00e1 suficiente si los pa\u00edses enfocan las metas y los objetivos de manera puramente cuantitativa, dejando de lado los derechos humanos al agua y al saneamiento\u201d, concluy\u00f3 el relator, llamando a acelerar los esfuerzos para alcanzar esos derechos para todos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con informaci\u00f3n de: ONU NOTICIAS<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.alcaldesdemexico.com\/notas-principales\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/\">https:\/\/www.alcaldesdemexico.com\/notas-principales\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ONU reconoci\u00f3 expl\u00edcitamente hace diez a\u00f1os el agua y el saneamiento como derechos humanos; sin embargo, miles de millones de personas carecen todav\u00eda de acceso a esos servicios b\u00e1sicos para su bienestar y su salud, lament\u00f3 el relator especial sobre esas garant\u00edas fundamentales.<\/p>\n","protected":false},"author":2873,"featured_media":14961,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[2429],"class_list":["post-14960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-saneamiento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Falta de agua y saneamiento provoca tragedias humanas: ONU - Aladyr<\/title>\n<meta name=\"description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Falta de agua y saneamiento provoca tragedias humanas: ONU - Aladyr\" \/>\n<meta property=\"og:description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/\" \/>\n<meta property=\"og:site_name\" content=\"Aladyr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionaladyr\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-31T13:40:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-31T13:41:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/07\/Saneamiento_Agua_ONU.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"798\" \/>\n\t<meta property=\"og:image:height\" content=\"460\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:site\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\\\/\"},\"author\":{\"name\":\"Diego Ortu\u00c3\u00b1o\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\"},\"headline\":\"Falta de agua y saneamiento provoca tragedias humanas: ONU\",\"datePublished\":\"2020-07-31T13:40:28+00:00\",\"dateModified\":\"2020-07-31T13:41:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\\\/\"},\"wordCount\":415,\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Saneamiento_Agua_ONU.jpg\",\"keywords\":[\"Saneamiento\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\\\/\",\"name\":\"Falta de agua y saneamiento provoca tragedias humanas: ONU - Aladyr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Saneamiento_Agua_ONU.jpg\",\"datePublished\":\"2020-07-31T13:40:28+00:00\",\"dateModified\":\"2020-07-31T13:41:53+00:00\",\"description\":\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Saneamiento_Agua_ONU.jpg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Saneamiento_Agua_ONU.jpg\",\"width\":798,\"height\":460},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Falta de agua y saneamiento provoca tragedias humanas: ONU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/\",\"name\":\"Aladyr\",\"description\":\"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua\",\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#organization\",\"name\":\"Aladyr\",\"url\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"width\":600,\"height\":400,\"caption\":\"Aladyr\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/asociacionaladyr\\\/\",\"https:\\\/\\\/x.com\\\/aladyr_asoc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aladyr\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGIYolI-td4K6GiafV32rA\",\"https:\\\/\\\/www.instagram.com\\\/aladyr_asociacion\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/pt-br\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\",\"name\":\"Diego Ortu\u00c3\u00b1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"caption\":\"Diego Ortu\u00c3\u00b1o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Falta de agua y saneamiento provoca tragedias humanas: ONU - Aladyr","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/","og_locale":"pt_BR","og_type":"article","og_title":"Falta de agua y saneamiento provoca tragedias humanas: ONU - Aladyr","og_description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","og_url":"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/","og_site_name":"Aladyr","article_publisher":"https:\/\/www.facebook.com\/asociacionaladyr\/","article_published_time":"2020-07-31T13:40:28+00:00","article_modified_time":"2020-07-31T13:41:53+00:00","og_image":[{"width":798,"height":460,"url":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/07\/Saneamiento_Agua_ONU.jpg","type":"image\/jpeg"}],"author":"Diego Ortu\u00c3\u00b1o","twitter_card":"summary_large_image","twitter_creator":"@aladyr_asoc","twitter_site":"@aladyr_asoc","twitter_misc":{"Escrito por":"Diego Ortu\u00c3\u00b1o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/#article","isPartOf":{"@id":"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/"},"author":{"name":"Diego Ortu\u00c3\u00b1o","@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f"},"headline":"Falta de agua y saneamiento provoca tragedias humanas: ONU","datePublished":"2020-07-31T13:40:28+00:00","dateModified":"2020-07-31T13:41:53+00:00","mainEntityOfPage":{"@id":"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/"},"wordCount":415,"publisher":{"@id":"https:\/\/aladyr.net\/pt-br\/#organization"},"image":{"@id":"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/07\/Saneamiento_Agua_ONU.jpg","keywords":["Saneamiento"],"articleSection":["Noticias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/","url":"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/","name":"Falta de agua y saneamiento provoca tragedias humanas: ONU - Aladyr","isPartOf":{"@id":"https:\/\/aladyr.net\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/#primaryimage"},"image":{"@id":"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/07\/Saneamiento_Agua_ONU.jpg","datePublished":"2020-07-31T13:40:28+00:00","dateModified":"2020-07-31T13:41:53+00:00","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","breadcrumb":{"@id":"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/#primaryimage","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/07\/Saneamiento_Agua_ONU.jpg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/07\/Saneamiento_Agua_ONU.jpg","width":798,"height":460},{"@type":"BreadcrumbList","@id":"https:\/\/aladyr.net\/pt-br\/falta-de-agua-y-saneamiento-provoca-tragedias-humanas-onu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aladyr.net\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Falta de agua y saneamiento provoca tragedias humanas: ONU"}]},{"@type":"WebSite","@id":"https:\/\/aladyr.net\/pt-br\/#website","url":"https:\/\/aladyr.net\/pt-br\/","name":"Aladyr","description":"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua","publisher":{"@id":"https:\/\/aladyr.net\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aladyr.net\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/aladyr.net\/pt-br\/#organization","name":"Aladyr","url":"https:\/\/aladyr.net\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","width":600,"height":400,"caption":"Aladyr"},"image":{"@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/asociacionaladyr\/","https:\/\/x.com\/aladyr_asoc","https:\/\/www.linkedin.com\/company\/aladyr","https:\/\/www.youtube.com\/channel\/UCeGIYolI-td4K6GiafV32rA","https:\/\/www.instagram.com\/aladyr_asociacion\/"]},{"@type":"Person","@id":"https:\/\/aladyr.net\/pt-br\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f","name":"Diego Ortu\u00c3\u00b1o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","caption":"Diego Ortu\u00c3\u00b1o"}}]}},"_links":{"self":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/posts\/14960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/users\/2873"}],"replies":[{"embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/comments?post=14960"}],"version-history":[{"count":0,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/posts\/14960\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/media\/14961"}],"wp:attachment":[{"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/media?parent=14960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/categories?post=14960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aladyr.net\/pt-br\/wp-json\/wp\/v2\/tags?post=14960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}