{"id":31705,"date":"2022-09-22T11:23:49","date_gmt":"2022-09-22T15:23:49","guid":{"rendered":"https:\/\/aladyr.net\/?p=31705"},"modified":"2022-09-22T11:23:55","modified_gmt":"2022-09-22T15:23:55","slug":"tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro","status":"publish","type":"post","link":"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/","title":{"rendered":"<strong>Tedagua contin\u00faa ayudando a frenar la emergencia h\u00eddrica de las islas Canarias, con una planta desaladora en El Hierro<\/strong>"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">21 de septiembre del 2022<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"463\" src=\"https:\/\/aladyr.net\/wp-content\/uploads\/2022\/09\/image-1.png\" alt=\"\" class=\"wp-image-31706\" srcset=\"https:\/\/aladyr.net\/wp-content\/uploads\/2022\/09\/image-1.png 768w, https:\/\/aladyr.net\/wp-content\/uploads\/2022\/09\/image-1-300x181.png 300w, https:\/\/aladyr.net\/wp-content\/uploads\/2022\/09\/image-1-100x60.png 100w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>La ausencia de lluvias provoc\u00f3 en la isla un notable descenso de los niveles de agua disponible para el riego de plantas y cultivos, lo que pon\u00eda en riesgo el principal motor econ\u00f3mico de la isla<\/strong><\/li><li><strong>Se instal\u00f3 en tiempo record una planta desaladora de agua de mar en formato contenedor de 1.200 m3\/d\u00eda de agua producto en el municipio de Frontera (El Hierro)<\/strong><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Tras m\u00e1s de dos meses en funcionamiento la planta desaladora contenerizada que Tedagua instal\u00f3 en la isla de El Hierro contin\u00faa ayudando a frenar la emergencia h\u00eddrica declarada en la isla el pasado mes de junio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ausencia de lluvias provoc\u00f3 en la isla un notable descenso de los niveles de agua disponible para el riego de plantas y cultivos, lo que pon\u00eda en riesgo el principal motor econ\u00f3mico de la isla. Este hecho movi\u00f3 al Consejo Insular de Aguas de El Hierro a cursar una solicitud para solucionar este problema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TEDAGUA puso a disposici\u00f3n de la isla, una planta desaladora en formato contenedor de 1.200 m3\/d\u00eda de agua producto. En tiempo record, se coloc\u00f3 la EDAM en Frontera (El Hierro) el 13 de junio, empezando con los ajustes seg\u00fan la captaci\u00f3n existente y las pruebas de puesta en marcha. El 14 de julio se empez\u00f3 a producir agua desalada para riego.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La planta utiliza la tecnolog\u00eda de \u00f3smosis inversa para producir agua producto, transformando el agua salada del mar. Su construcci\u00f3n en formato contenedor facilita su transporte e instalaci\u00f3n, adem\u00e1s de tener un reducido impacto en el medio ambiente. Hasta la fecha la instalaci\u00f3n est\u00e1 generando los caudales solicitados por el cliente, con previsi\u00f3n de estar en funcionamiento hasta noviembre de este a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este hito se cumple justo un a\u00f1o despu\u00e9s de la construcci\u00f3n por parte de Tedagua de dos plantas desaladoras de emergencia de 2.600 m3\/d\u00eda en la isla de La Palma, tambi\u00e9n en un tiempo r\u00e9cord, tras la erupci\u00f3n del volc\u00e1n de Cumbre Vieja. Gracias a ello se logr\u00f3 salvar la producci\u00f3n de m\u00faltiples cosechas de pl\u00e1tanos de los efectos de dicho desastre natural y se suma a otras plantas modulares construidas recientemente, como las seis plantas de 1.000 m3\/d\u00eda instaladas en Fuerteventura para abastecimiento de agua potable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos logros son un ejemplo del compromiso de Tedagua con la poblaci\u00f3n y las Administraciones de las islas Canarias, poniendo a su disposici\u00f3n soluciones t\u00e9cnicas viables y de r\u00e1pida respuesta ante los desaf\u00edos de la escasez h\u00eddrica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras m\u00e1s de dos meses en funcionamiento la planta desaladora contenerizada que Tedagua instal\u00f3 en la isla de El Hierro contin\u00faa ayudando a frenar la emergencia h\u00eddrica declarada en la isla el pasado mes de junio.<\/p>\n","protected":false},"author":2873,"featured_media":31706,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-31705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tedagua contin\u00faa ayudando a frenar la emergencia h\u00eddrica de las islas Canarias, con una planta desaladora en El Hierro - Aladyr<\/title>\n<meta name=\"description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tedagua contin\u00faa ayudando a frenar la emergencia h\u00eddrica de las islas Canarias, con una planta desaladora en El Hierro - Aladyr\" \/>\n<meta property=\"og:description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/\" \/>\n<meta property=\"og:site_name\" content=\"Aladyr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionaladyr\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-22T15:23:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-22T15:23:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aladyr.net\/wp-content\/uploads\/2022\/09\/image-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"463\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:site\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\\\/\"},\"author\":{\"name\":\"Diego Ortu\u00c3\u00b1o\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\"},\"headline\":\"Tedagua contin\u00faa ayudando a frenar la emergencia h\u00eddrica de las islas Canarias, con una planta desaladora en El Hierro\",\"datePublished\":\"2022-09-22T15:23:49+00:00\",\"dateModified\":\"2022-09-22T15:23:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\\\/\"},\"wordCount\":461,\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/image-1.png\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/en\\\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\\\/\",\"name\":\"Tedagua contin\u00faa ayudando a frenar la emergencia h\u00eddrica de las islas Canarias, con una planta desaladora en El Hierro - Aladyr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/image-1.png\",\"datePublished\":\"2022-09-22T15:23:49+00:00\",\"dateModified\":\"2022-09-22T15:23:55+00:00\",\"description\":\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aladyr.net\\\/en\\\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/image-1.png\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/image-1.png\",\"width\":768,\"height\":463},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aladyr.net\\\/en\\\/homepage-2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tedagua contin\u00faa ayudando a frenar la emergencia h\u00eddrica de las islas Canarias, con una planta desaladora en El Hierro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/aladyr.net\\\/en\\\/\",\"name\":\"Aladyr\",\"description\":\"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua\",\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aladyr.net\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#organization\",\"name\":\"Aladyr\",\"url\":\"https:\\\/\\\/aladyr.net\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"width\":600,\"height\":400,\"caption\":\"Aladyr\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/asociacionaladyr\\\/\",\"https:\\\/\\\/x.com\\\/aladyr_asoc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aladyr\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGIYolI-td4K6GiafV32rA\",\"https:\\\/\\\/www.instagram.com\\\/aladyr_asociacion\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\",\"name\":\"Diego Ortu\u00c3\u00b1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"caption\":\"Diego Ortu\u00c3\u00b1o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tedagua contin\u00faa ayudando a frenar la emergencia h\u00eddrica de las islas Canarias, con una planta desaladora en El Hierro - Aladyr","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/","og_locale":"en_US","og_type":"article","og_title":"Tedagua contin\u00faa ayudando a frenar la emergencia h\u00eddrica de las islas Canarias, con una planta desaladora en El Hierro - Aladyr","og_description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","og_url":"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/","og_site_name":"Aladyr","article_publisher":"https:\/\/www.facebook.com\/asociacionaladyr\/","article_published_time":"2022-09-22T15:23:49+00:00","article_modified_time":"2022-09-22T15:23:55+00:00","og_image":[{"width":768,"height":463,"url":"https:\/\/aladyr.net\/wp-content\/uploads\/2022\/09\/image-1.png","type":"image\/png"}],"author":"Diego Ortu\u00c3\u00b1o","twitter_card":"summary_large_image","twitter_creator":"@aladyr_asoc","twitter_site":"@aladyr_asoc","twitter_misc":{"Written by":"Diego Ortu\u00c3\u00b1o","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/#article","isPartOf":{"@id":"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/"},"author":{"name":"Diego Ortu\u00c3\u00b1o","@id":"https:\/\/aladyr.net\/en\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f"},"headline":"Tedagua contin\u00faa ayudando a frenar la emergencia h\u00eddrica de las islas Canarias, con una planta desaladora en El Hierro","datePublished":"2022-09-22T15:23:49+00:00","dateModified":"2022-09-22T15:23:55+00:00","mainEntityOfPage":{"@id":"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/"},"wordCount":461,"publisher":{"@id":"https:\/\/aladyr.net\/en\/#organization"},"image":{"@id":"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2022\/09\/image-1.png","articleSection":["Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/","url":"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/","name":"Tedagua contin\u00faa ayudando a frenar la emergencia h\u00eddrica de las islas Canarias, con una planta desaladora en El Hierro - Aladyr","isPartOf":{"@id":"https:\/\/aladyr.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/#primaryimage"},"image":{"@id":"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2022\/09\/image-1.png","datePublished":"2022-09-22T15:23:49+00:00","dateModified":"2022-09-22T15:23:55+00:00","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","breadcrumb":{"@id":"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/#primaryimage","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2022\/09\/image-1.png","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2022\/09\/image-1.png","width":768,"height":463},{"@type":"BreadcrumbList","@id":"https:\/\/aladyr.net\/en\/tedagua-continua-ayudando-a-frenar-la-emergencia-hidrica-de-las-islas-canarias-con-una-planta-desaladora-en-el-hierro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aladyr.net\/en\/homepage-2025\/"},{"@type":"ListItem","position":2,"name":"Tedagua contin\u00faa ayudando a frenar la emergencia h\u00eddrica de las islas Canarias, con una planta desaladora en El Hierro"}]},{"@type":"WebSite","@id":"https:\/\/aladyr.net\/en\/#website","url":"https:\/\/aladyr.net\/en\/","name":"Aladyr","description":"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua","publisher":{"@id":"https:\/\/aladyr.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aladyr.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/aladyr.net\/en\/#organization","name":"Aladyr","url":"https:\/\/aladyr.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aladyr.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","width":600,"height":400,"caption":"Aladyr"},"image":{"@id":"https:\/\/aladyr.net\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/asociacionaladyr\/","https:\/\/x.com\/aladyr_asoc","https:\/\/www.linkedin.com\/company\/aladyr","https:\/\/www.youtube.com\/channel\/UCeGIYolI-td4K6GiafV32rA","https:\/\/www.instagram.com\/aladyr_asociacion\/"]},{"@type":"Person","@id":"https:\/\/aladyr.net\/en\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f","name":"Diego Ortu\u00c3\u00b1o","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","caption":"Diego Ortu\u00c3\u00b1o"}}]}},"_links":{"self":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/posts\/31705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/users\/2873"}],"replies":[{"embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/comments?post=31705"}],"version-history":[{"count":0,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/posts\/31705\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/media\/31706"}],"wp:attachment":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/media?parent=31705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/categories?post=31705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/tags?post=31705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}