{"id":20206,"date":"2021-01-20T11:46:58","date_gmt":"2021-01-20T15:46:58","guid":{"rendered":"https:\/\/aladyr.net\/?p=20206"},"modified":"2021-01-20T11:49:23","modified_gmt":"2021-01-20T15:49:23","slug":"aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021","status":"publish","type":"post","link":"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/","title":{"rendered":"AEDyR: LANZAMIENTO DEL PRIMER CONGRESO DIGITAL \u2013Febrero-Junio2021"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/aladyr.net\/wp-content\/uploads\/2021\/01\/AEDYR_HD-1024x576.jpg\" alt=\"El Primer Congreso Digital de Desalaci\u00f3n y Reutilizaci\u00f3n de Agua surge por la necesidad del sector de poder mostrar sus novedades e innovaciones. Esta primera edici\u00f3n viene a completar la celebraci\u00f3n de nuestro XIII Congreso Internacional que celebraremos en la ciudad de C\u00f3rdoba en el a\u00f1o 2022.\" class=\"wp-image-20202\" srcset=\"https:\/\/aladyr.net\/wp-content\/uploads\/2021\/01\/AEDYR_HD-1024x576.jpg 1024w, https:\/\/aladyr.net\/wp-content\/uploads\/2021\/01\/AEDYR_HD-300x169.jpg 300w, https:\/\/aladyr.net\/wp-content\/uploads\/2021\/01\/AEDYR_HD-768x432.jpg 768w, https:\/\/aladyr.net\/wp-content\/uploads\/2021\/01\/AEDYR_HD-1536x864.jpg 1536w, https:\/\/aladyr.net\/wp-content\/uploads\/2021\/01\/AEDYR_HD-100x56.jpg 100w, https:\/\/aladyr.net\/wp-content\/uploads\/2021\/01\/AEDYR_HD-1200x675.jpg 1200w, https:\/\/aladyr.net\/wp-content\/uploads\/2021\/01\/AEDYR_HD.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">El Primer Congreso Digital de Desalaci\u00f3n y Reutilizaci\u00f3n de Agua surge por la necesidad del sector de poder mostrar sus novedades e innovaciones. Esta primera edici\u00f3n viene a completar la celebraci\u00f3n de nuestro XIII Congreso Internacional que celebraremos en la ciudad de C\u00f3rdoba en el a\u00f1o 2022.<br>El Congreso tiene como objetivo ofrecer un foro internacional donde poner en contacto a los expertos en desalaci\u00f3n, reutilizaci\u00f3n y tratamiento de aguas, tanto de empresas, instituciones p\u00fablicas, como universidades y centros de investigaci\u00f3n, con el fin de presentar las \u00faltimas innovaciones, investigaciones y desarrollos en estos campos, fomentando el di\u00e1logo, la colaboraci\u00f3n y el intercambio de experiencias, t\u00e9cnicas e ideas entre profesionales.<br>Este Primer Congreso Digital estar\u00e1 dividido en seis interesantes sesiones en un periodo comprendido en cinco meses: la primera sesi\u00f3n tendr\u00e1 lugar en febrero 2021 y la \u00faltima en junio 2021.<br><strong>Res\u00e9rvese las fechas<\/strong><br>Las fechas de celebraci\u00f3n de las seis sesiones ser\u00e1n las siguientes: Sesi\u00f3n 1: Mi\u00e9rcoles 17 de febrero; Sesi\u00f3n 2: Mi\u00e9rcoles 10 de marzo; Sesi\u00f3n 3: Mi\u00e9rcoles 31 de marzo; Sesi\u00f3n 4: Mi\u00e9rcoles 14 de abril; Sesi\u00f3n 5: Mi\u00e9rcoles 26 de mayo; Sesi\u00f3n 6: Mi\u00e9rcoles 23 de junio.<br>A la vez hemos querido concentrar en cada sesi\u00f3n las ponencias bajo bloques tem\u00e1ticos diferenciados, que ser\u00e1n los siguientes:<br>Sesi\u00f3n1: En b\u00fasqueda de la econom\u00eda circular: optimizaci\u00f3n de los procesos y eficiencia energ\u00e9tica; Sesi\u00f3n2: Materiales y equipos: evoluci\u00f3n y mejoras; Sesi\u00f3n3: Avances en procesos y desarrollo de productos qu\u00edmicos; Sesi\u00f3n4: Digitalizaci\u00f3n en el mercado del agua y monogr\u00e1fico eliminaci\u00f3n de contaminantes; Sesi\u00f3n5: Innovaciones I+D; Sesi\u00f3n6: Proyectos de desalaci\u00f3n y<br>reutilizaci\u00f3n: experiencias y lecciones aprendidas.<br>A modo de avance la primera sesi\u00f3n que se celebrar\u00e1 el pr\u00f3ximo 17 de febrero, contar\u00e1 con seis ponentes de gran conocimiento y prestigio del sector donde se hablar\u00e1 sobre la optimizaci\u00f3n de los procesos y la eficiencia energ\u00e9tica.<br>A continuaci\u00f3n, participar\u00e1 como invitado especial el Gerente de Econssa Chile, Patricio Herrera, que nos hablar\u00e1 sobre las \u201cCondiciones a adoptar por Chile para contemplar la desalaci\u00f3n como una de sus principales soluciones ante la escasez h\u00eddrica\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como broche final, se llevar\u00e1 a cabo una apasionante mesa redonda titulada: \u201cEl mercado actual de desalaci\u00f3n en Latinoam\u00e9rica: Infraestructuras y Tecnolog\u00eda\u201d que contar\u00e1 con la participaci\u00f3n de los representantes de las empresas m\u00e1s importantes del sector del agua debati\u00e9ndose temas de contenido muy diversos enfocados a los retos, oportunidades y transformaci\u00f3n del sector.<br>Este Primer Congreso Digital cuenta con la colaboraci\u00f3n de SACYR AGUA CONCESIONES y el Patrocinio Oro de DANFOSS en la sesi\u00f3n 2 sobre Materiales y equipos: evoluci\u00f3n y mejoras y, con el apoyo especial de las revistas\/portales m\u00e1s influyentes del sector: FUTURENVIRO, REVISTA PQ, AGUAS RESIDUALES, RETEMA, INTEREMPRESAS, BLOG DEL AGUA y TECNOAQUA.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el enlace<a href=\"https:\/\/aedyr.com\/congresos\/i-congreso-digital-aedy\"> <\/a><a href=\"https:\/\/aedyr.com\/congresos\/i-congreso-digital-aedy\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/aedyr.com\/congresos\/i-congreso-digital-aedyr<\/a> encontrar\u00e1 de manera pormenorizada toda la informaci\u00f3n relacionada con este evento.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Madrid, 20 de enero 2021<br>Contactos de prensa:<br>Luz Nogales<br>Comunicaci\u00f3n<br>aedyr@aedyr.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Primer Congreso Digital de Desalaci\u00f3n y Reutilizaci\u00f3n de Agua surge por la necesidad del sector de poder mostrar sus novedades e innovaciones. Esta primera edici\u00f3n viene a completar la celebraci\u00f3n de nuestro XIII Congreso Internacional que celebraremos en la ciudad de C\u00f3rdoba en el a\u00f1o 2022.<\/p>\n","protected":false},"author":2873,"featured_media":20202,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[],"class_list":["post-20206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AEDyR: LANZAMIENTO DEL PRIMER CONGRESO DIGITAL \u2013Febrero-Junio2021 - Aladyr<\/title>\n<meta name=\"description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AEDyR: LANZAMIENTO DEL PRIMER CONGRESO DIGITAL \u2013Febrero-Junio2021 - Aladyr\" \/>\n<meta property=\"og:description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Aladyr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionaladyr\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-20T15:46:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-20T15:49:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aladyr.net\/wp-content\/uploads\/2021\/01\/AEDYR_HD.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:site\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\\\/\"},\"author\":{\"name\":\"Diego Ortu\u00c3\u00b1o\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\"},\"headline\":\"AEDyR: LANZAMIENTO DEL PRIMER CONGRESO DIGITAL \u2013Febrero-Junio2021\",\"datePublished\":\"2021-01-20T15:46:58+00:00\",\"dateModified\":\"2021-01-20T15:49:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\\\/\"},\"wordCount\":537,\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/AEDYR_HD.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/en\\\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\\\/\",\"name\":\"AEDyR: LANZAMIENTO DEL PRIMER CONGRESO DIGITAL \u2013Febrero-Junio2021 - Aladyr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/AEDYR_HD.jpg\",\"datePublished\":\"2021-01-20T15:46:58+00:00\",\"dateModified\":\"2021-01-20T15:49:23+00:00\",\"description\":\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aladyr.net\\\/en\\\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/AEDYR_HD.jpg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/AEDYR_HD.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aladyr.net\\\/en\\\/homepage-2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AEDyR: LANZAMIENTO DEL PRIMER CONGRESO DIGITAL \u2013Febrero-Junio2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/aladyr.net\\\/en\\\/\",\"name\":\"Aladyr\",\"description\":\"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua\",\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aladyr.net\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#organization\",\"name\":\"Aladyr\",\"url\":\"https:\\\/\\\/aladyr.net\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"width\":600,\"height\":400,\"caption\":\"Aladyr\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/asociacionaladyr\\\/\",\"https:\\\/\\\/x.com\\\/aladyr_asoc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aladyr\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGIYolI-td4K6GiafV32rA\",\"https:\\\/\\\/www.instagram.com\\\/aladyr_asociacion\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\",\"name\":\"Diego Ortu\u00c3\u00b1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"caption\":\"Diego Ortu\u00c3\u00b1o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AEDyR: LANZAMIENTO DEL PRIMER CONGRESO DIGITAL \u2013Febrero-Junio2021 - Aladyr","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/","og_locale":"en_US","og_type":"article","og_title":"AEDyR: LANZAMIENTO DEL PRIMER CONGRESO DIGITAL \u2013Febrero-Junio2021 - Aladyr","og_description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","og_url":"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/","og_site_name":"Aladyr","article_publisher":"https:\/\/www.facebook.com\/asociacionaladyr\/","article_published_time":"2021-01-20T15:46:58+00:00","article_modified_time":"2021-01-20T15:49:23+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/aladyr.net\/wp-content\/uploads\/2021\/01\/AEDYR_HD.jpg","type":"image\/jpeg"}],"author":"Diego Ortu\u00c3\u00b1o","twitter_card":"summary_large_image","twitter_creator":"@aladyr_asoc","twitter_site":"@aladyr_asoc","twitter_misc":{"Written by":"Diego Ortu\u00c3\u00b1o","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/#article","isPartOf":{"@id":"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/"},"author":{"name":"Diego Ortu\u00c3\u00b1o","@id":"https:\/\/aladyr.net\/en\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f"},"headline":"AEDyR: LANZAMIENTO DEL PRIMER CONGRESO DIGITAL \u2013Febrero-Junio2021","datePublished":"2021-01-20T15:46:58+00:00","dateModified":"2021-01-20T15:49:23+00:00","mainEntityOfPage":{"@id":"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/"},"wordCount":537,"publisher":{"@id":"https:\/\/aladyr.net\/en\/#organization"},"image":{"@id":"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2021\/01\/AEDYR_HD.jpg","articleSection":["Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/","url":"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/","name":"AEDyR: LANZAMIENTO DEL PRIMER CONGRESO DIGITAL \u2013Febrero-Junio2021 - Aladyr","isPartOf":{"@id":"https:\/\/aladyr.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/#primaryimage"},"image":{"@id":"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2021\/01\/AEDYR_HD.jpg","datePublished":"2021-01-20T15:46:58+00:00","dateModified":"2021-01-20T15:49:23+00:00","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","breadcrumb":{"@id":"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/#primaryimage","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2021\/01\/AEDYR_HD.jpg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2021\/01\/AEDYR_HD.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/aladyr.net\/en\/aedyr-lanzamiento-del-primer-congreso-digital-febrero-junio2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aladyr.net\/en\/homepage-2025\/"},{"@type":"ListItem","position":2,"name":"AEDyR: LANZAMIENTO DEL PRIMER CONGRESO DIGITAL \u2013Febrero-Junio2021"}]},{"@type":"WebSite","@id":"https:\/\/aladyr.net\/en\/#website","url":"https:\/\/aladyr.net\/en\/","name":"Aladyr","description":"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua","publisher":{"@id":"https:\/\/aladyr.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aladyr.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/aladyr.net\/en\/#organization","name":"Aladyr","url":"https:\/\/aladyr.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aladyr.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","width":600,"height":400,"caption":"Aladyr"},"image":{"@id":"https:\/\/aladyr.net\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/asociacionaladyr\/","https:\/\/x.com\/aladyr_asoc","https:\/\/www.linkedin.com\/company\/aladyr","https:\/\/www.youtube.com\/channel\/UCeGIYolI-td4K6GiafV32rA","https:\/\/www.instagram.com\/aladyr_asociacion\/"]},{"@type":"Person","@id":"https:\/\/aladyr.net\/en\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f","name":"Diego Ortu\u00c3\u00b1o","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","caption":"Diego Ortu\u00c3\u00b1o"}}]}},"_links":{"self":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/posts\/20206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/users\/2873"}],"replies":[{"embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/comments?post=20206"}],"version-history":[{"count":0,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/posts\/20206\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/media\/20202"}],"wp:attachment":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/media?parent=20206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/categories?post=20206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/tags?post=20206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}