{"id":18574,"date":"2020-11-17T09:45:38","date_gmt":"2020-11-17T13:45:38","guid":{"rendered":"https:\/\/aladyr.net\/?p=18574"},"modified":"2020-11-17T09:45:41","modified_gmt":"2020-11-17T13:45:41","slug":"la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile","status":"publish","type":"post","link":"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/","title":{"rendered":"La desalaci\u00f3n y el re\u00faso son ineludibles para garantizar la seguridad h\u00eddrica de Chile"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Juan Miguel Pinto, Presidente de la Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua,\u00a0 ALADYR<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/foro_chile_home-1-1024x576.jpg\" alt=\"\" class=\"wp-image-17405\" srcset=\"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/foro_chile_home-1-1024x576.jpg 1024w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/foro_chile_home-1-300x169.jpg 300w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/foro_chile_home-1-768x432.jpg 768w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/foro_chile_home-1-1536x864.jpg 1536w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/foro_chile_home-1-100x56.jpg 100w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/foro_chile_home-1-1200x675.jpg 1200w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/foro_chile_home-1.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En Chile la discusi\u00f3n sobre la desalaci\u00f3n de agua de mar y el re\u00faso de agua ya trascendi\u00f3 las cuestiones fundamentales sobre su idoneidad y la necesidad de su incorporaci\u00f3n. Ya sabemos que son procesos imprescindibles para lograr la seguridad h\u00eddrica y la realidad objetiva nos compele a decir que esta afirmaci\u00f3n es innegable. Lo que cabe discutir es cu\u00e1l es el marco regulatorio propicio para fomentar la integraci\u00f3n de estas tecnolog\u00edas y potenciar otros sectores productivos m\u00e1s all\u00e1 de la Gran Miner\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las condiciones objetivas son clim\u00e1ticas, econ\u00f3micas y &nbsp;demogr\u00e1ficas. Su veracidad no puede ser negada y mucho menos sus consecuencias. La poblaci\u00f3n ha aumentado, hay mayor actividad econ\u00f3mica y mayor demanda de agua. Adem\u00e1s existen pruebas fehacientes &nbsp;de que la disponibilidad del recurso es menor por razones del cambio clim\u00e1tico y calidad del mismo. Por consiguiente, esto nos obliga a buscar otras fuentes de agua como la desalaci\u00f3n de agua de mar y el re\u00faso porque los paradigmas de la reducci\u00f3n del consumo, especialmente a nivel dom\u00e9stico, o conservaci\u00f3n son &nbsp;insuficientes para alcanzar la meta final. &nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entonces, como sociedad es necesario &nbsp;pensar de qu\u00e9 manera debemos configurar nuestras normas para atender a esta realidad en la proporci\u00f3n que demanda. No solo&nbsp; es Chile, &nbsp;el mundo tambi\u00e9n est\u00e1 entendiendo que no puede aplazar la integraci\u00f3n de las soluciones tecnol\u00f3gicas para garantizar la disponibilidad h\u00eddrica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La falta de agua impuesta por el cambio clim\u00e1tico perjudica notablemente a la actividad agr\u00edcola y comienza a hacerse sentir tambi\u00e9n en otros sectores de la econom\u00eda e incluso en el abastecimiento de agua potable para la poblaci\u00f3n, sobre todo en Sistemas de Agua Potable Rural, aunque tambi\u00e9n en algunas \u00e1reas urbanas (Ej.: Valle de Petorca). Sin embargo, algunos de los principales problemas de suministro de agua en Chile pueden ser solucionados de manera efectiva a trav\u00e9s de la desalaci\u00f3n y el re\u00faso del agua; as\u00ed lo demuestra el amplio avance de la actividad minera gracias a la integraci\u00f3n de las tecnolog\u00edas de tratamiento de agua. Pero, tanto la desalaci\u00f3n como el re\u00faso de agua enfrentan obst\u00e1culos que dificultan su desarrollo en el pa\u00eds y demoran la materializaci\u00f3n de los proyectos. La mejor forma de permitir el alcance de estos es mediante la actualizaci\u00f3n de procedimientos, normativas y requerimientos que posibiliten generar nuevas fuentes de agua para la industria y uso potable, establecer medidas de uso eficiente del recurso a nivel industrial y definir tarifas del agua equivalentes a inversiones adecuadas en tecnolog\u00edas y actualizaciones, entre otros. Se trata de una cadena de acciones que van de la mano y que deben ser atendidas con urgencia y prioridad.<\/p>\n\n\n\n<figure class=\"wp-block-pullquote has-background has-pale-cyan-blue-background-color is-style-solid-color\"><blockquote class=\"has-text-color has-very-dark-gray-color\"><p>La Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua (ALADYR) realizar\u00e1 el 18 y 19 de noviembre el FORO ONLINE<strong> \u201cPOL\u00cdTICAS P\u00daBLICAS PARA GARANTIZAR EL ACCESO AL AGUA. Desalaci\u00f3n y Re\u00faso, Soluciones para CHILE\u201d<\/strong>, que es de acceso gratuito para todos los asistentes a fin de incentivar la participaci\u00f3n en la din\u00e1mica y lograr la difusi\u00f3n masiva del mensaje ALADYR \u201cgarantizar el acceso al agua potable y uso eficiente y sostenible del recurso h\u00eddrico mediante la integraci\u00f3n de las tecnolog\u00edas de desalaci\u00f3n, re\u00faso y tratamiento de agua y efluentes\u201d.\u00a0<\/p><p>\u00a0<\/p><p>Entre los participantes destacan el <strong>Ministro de Econom\u00eda de Chile, Lucas Palacios<\/strong>; \u00a0Carlos Cos\u00edn, presidente de la Asociaci\u00f3n Internacional de Desalinizaci\u00f3n (IDA por sus siglas en ingl\u00e9s); Domingo Zarzo, presidente de la Asociaci\u00f3n Espa\u00f1ola de Desalaci\u00f3n y Re\u00faso de Agua (AEDyR); Joaqu\u00edn Villarino, presidente ejecutivo del Consejo Minero de Chile; Marta Colet gerenta general de Aguas Andinas y Carmen Lacoma gerenta general CETAQUA, s\u00f3lo por mencionar a algunos de los quince panelistas que conforman la agenda del evento.<\/p><p>\u00a0<\/p><p>MAS INFORMACI\u00d3N: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 www.aladyr.net<\/p><\/blockquote><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Ya sabemos que la desalaci\u00f3n y el re\u00faso son imprescindibles para lograr la seguridad h\u00eddrica y la realidad objetiva nos compele a decir que esta afirmaci\u00f3n es innegable. Lo que cabe discutir es cu\u00e1l es el marco regulatorio propicio para fomentar la integraci\u00f3n de estas tecnolog\u00edas y potenciar otros sectores productivos m\u00e1s all\u00e1 de la Gran Miner\u00eda.<\/p>\n","protected":false},"author":2873,"featured_media":17405,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[2716,2929,1879,1880,3378],"class_list":["post-18574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-chile","tag-crisis-hidrica","tag-desalacion","tag-reuso-de-agua","tag-sequia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La desalaci\u00f3n y el re\u00faso son ineludibles para garantizar la seguridad h\u00eddrica de Chile - Aladyr<\/title>\n<meta name=\"description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La desalaci\u00f3n y el re\u00faso son ineludibles para garantizar la seguridad h\u00eddrica de Chile - Aladyr\" \/>\n<meta property=\"og:description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/\" \/>\n<meta property=\"og:site_name\" content=\"Aladyr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionaladyr\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-17T13:45:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-17T13:45:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/foro_chile_home-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:site\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\\\/\"},\"author\":{\"name\":\"Diego Ortu\u00c3\u00b1o\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\"},\"headline\":\"La desalaci\u00f3n y el re\u00faso son ineludibles para garantizar la seguridad h\u00eddrica de Chile\",\"datePublished\":\"2020-11-17T13:45:38+00:00\",\"dateModified\":\"2020-11-17T13:45:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\\\/\"},\"wordCount\":719,\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/foro_chile_home-1.jpg\",\"keywords\":[\"Chile\",\"crisis h\u00eddrica\",\"desalaci\u00f3n\",\"re\u00faso de agua\",\"sequ\u00eda\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/en\\\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\\\/\",\"name\":\"La desalaci\u00f3n y el re\u00faso son ineludibles para garantizar la seguridad h\u00eddrica de Chile - Aladyr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/foro_chile_home-1.jpg\",\"datePublished\":\"2020-11-17T13:45:38+00:00\",\"dateModified\":\"2020-11-17T13:45:41+00:00\",\"description\":\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aladyr.net\\\/en\\\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/foro_chile_home-1.jpg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/foro_chile_home-1.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aladyr.net\\\/en\\\/homepage-2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La desalaci\u00f3n y el re\u00faso son ineludibles para garantizar la seguridad h\u00eddrica de Chile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/aladyr.net\\\/en\\\/\",\"name\":\"Aladyr\",\"description\":\"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua\",\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aladyr.net\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#organization\",\"name\":\"Aladyr\",\"url\":\"https:\\\/\\\/aladyr.net\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"width\":600,\"height\":400,\"caption\":\"Aladyr\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/asociacionaladyr\\\/\",\"https:\\\/\\\/x.com\\\/aladyr_asoc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aladyr\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGIYolI-td4K6GiafV32rA\",\"https:\\\/\\\/www.instagram.com\\\/aladyr_asociacion\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\",\"name\":\"Diego Ortu\u00c3\u00b1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"caption\":\"Diego Ortu\u00c3\u00b1o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La desalaci\u00f3n y el re\u00faso son ineludibles para garantizar la seguridad h\u00eddrica de Chile - Aladyr","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/","og_locale":"en_US","og_type":"article","og_title":"La desalaci\u00f3n y el re\u00faso son ineludibles para garantizar la seguridad h\u00eddrica de Chile - Aladyr","og_description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","og_url":"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/","og_site_name":"Aladyr","article_publisher":"https:\/\/www.facebook.com\/asociacionaladyr\/","article_published_time":"2020-11-17T13:45:38+00:00","article_modified_time":"2020-11-17T13:45:41+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/foro_chile_home-1.jpg","type":"image\/jpeg"}],"author":"Diego Ortu\u00c3\u00b1o","twitter_card":"summary_large_image","twitter_creator":"@aladyr_asoc","twitter_site":"@aladyr_asoc","twitter_misc":{"Written by":"Diego Ortu\u00c3\u00b1o","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/#article","isPartOf":{"@id":"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/"},"author":{"name":"Diego Ortu\u00c3\u00b1o","@id":"https:\/\/aladyr.net\/en\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f"},"headline":"La desalaci\u00f3n y el re\u00faso son ineludibles para garantizar la seguridad h\u00eddrica de Chile","datePublished":"2020-11-17T13:45:38+00:00","dateModified":"2020-11-17T13:45:41+00:00","mainEntityOfPage":{"@id":"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/"},"wordCount":719,"publisher":{"@id":"https:\/\/aladyr.net\/en\/#organization"},"image":{"@id":"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/foro_chile_home-1.jpg","keywords":["Chile","crisis h\u00eddrica","desalaci\u00f3n","re\u00faso de agua","sequ\u00eda"],"articleSection":["Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/","url":"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/","name":"La desalaci\u00f3n y el re\u00faso son ineludibles para garantizar la seguridad h\u00eddrica de Chile - Aladyr","isPartOf":{"@id":"https:\/\/aladyr.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/#primaryimage"},"image":{"@id":"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/foro_chile_home-1.jpg","datePublished":"2020-11-17T13:45:38+00:00","dateModified":"2020-11-17T13:45:41+00:00","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","breadcrumb":{"@id":"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/#primaryimage","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/foro_chile_home-1.jpg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/foro_chile_home-1.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/aladyr.net\/en\/la-desalacion-y-el-reuso-son-ineludibles-para-garantizar-la-seguridad-hidrica-de-chile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aladyr.net\/en\/homepage-2025\/"},{"@type":"ListItem","position":2,"name":"La desalaci\u00f3n y el re\u00faso son ineludibles para garantizar la seguridad h\u00eddrica de Chile"}]},{"@type":"WebSite","@id":"https:\/\/aladyr.net\/en\/#website","url":"https:\/\/aladyr.net\/en\/","name":"Aladyr","description":"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua","publisher":{"@id":"https:\/\/aladyr.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aladyr.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/aladyr.net\/en\/#organization","name":"Aladyr","url":"https:\/\/aladyr.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aladyr.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","width":600,"height":400,"caption":"Aladyr"},"image":{"@id":"https:\/\/aladyr.net\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/asociacionaladyr\/","https:\/\/x.com\/aladyr_asoc","https:\/\/www.linkedin.com\/company\/aladyr","https:\/\/www.youtube.com\/channel\/UCeGIYolI-td4K6GiafV32rA","https:\/\/www.instagram.com\/aladyr_asociacion\/"]},{"@type":"Person","@id":"https:\/\/aladyr.net\/en\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f","name":"Diego Ortu\u00c3\u00b1o","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","caption":"Diego Ortu\u00c3\u00b1o"}}]}},"_links":{"self":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/posts\/18574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/users\/2873"}],"replies":[{"embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/comments?post=18574"}],"version-history":[{"count":0,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/posts\/18574\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/media\/17405"}],"wp:attachment":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/media?parent=18574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/categories?post=18574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/tags?post=18574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}