{"id":17949,"date":"2020-10-22T09:12:08","date_gmt":"2020-10-22T13:12:08","guid":{"rendered":"https:\/\/aladyr.net\/?p=17949"},"modified":"2020-10-22T09:12:10","modified_gmt":"2020-10-22T13:12:10","slug":"unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039","status":"publish","type":"post","link":"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/","title":{"rendered":"Unilever explicar\u00e1 sus metas de compromiso ambiental para 2039"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">L\u00edder H2O contin\u00faa en Argentina<\/h2>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\"><p><strong><em>La compa\u00f1\u00eda concentra varias de las marcas m\u00e1s consumidas del mundo y tiene importantes objetivos de sustentabilidad que incluyen el re\u00faso de agua. Sobre esto y m\u00e1s se hablar\u00e1 en el ciclo de entrevistas interactivas \u201cL\u00edder H2O\u201d<\/em><\/strong><\/p><\/blockquote>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"492\" src=\"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/unilever.jpg\" alt=\"\" class=\"wp-image-17950\" srcset=\"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/unilever.jpg 940w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/unilever-300x157.jpg 300w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/unilever-768x402.jpg 768w, https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/unilever-100x52.jpg 100w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><figcaption>Foto cortes\u00eda Unilever<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prensa ALADYR &#8211;<\/strong> Unilever, compa\u00f1\u00eda l\u00edder de consumo masivo, expondr\u00e1 sus compromisos de clima y naturaleza anunciados recientemente en L\u00edder H2O, un espacio creado por la Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua (ALADYR) en labor conjunta con Futuro Sustentable desde Argentina. &nbsp;El objetivo es dar conocer las iniciativas en gesti\u00f3n del agua de los principales referentes de los sectores p\u00fablico y privado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ciclo de entrevistas comenz\u00f3 el pasado 24 de septiembre con Guillermo Jelinski, subsecretario de Recursos H\u00eddricos de la Provincia de Buenos Aires, quien disert\u00f3 sobre \u201cInversi\u00f3n y desaf\u00edos del nuevo plan de infraestructuras de agua y saneamiento para la provincia de Buenos Aires\u201d e intercambi\u00f3 ideas con representantes de importantes empresas. Durante el pr\u00f3ximo encuentro, estar\u00e1 participando Jordana Carvallo, Gerente de Medio Ambiente y Seguridad para el Cono Sur de Unilever; quien ser\u00e1 entrevistada por Pablo Gago, periodista de larga trayectoria en temas ambientales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La transmisi\u00f3n se har\u00e1 en vivo el pr\u00f3ximo 29 de octubre a trav\u00e9s del canal de YouTube de ALADYR y contar\u00e1 con participaciones especiales y un canal directo de preguntas y respuestas con la audiencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale mencionar que el ciclo de entrevistas cuenta con el apoyo de las empresas Atlantium Technologies, Aguas y Procesos, Fluence Corporation y Veolia Argentina, destacadas por promover tecnolog\u00edas y procesos rde e\u00faso, desalaci\u00f3n y tratamiento de aguas y efluentes para dotar de sostenibilidad h\u00eddrica a las actividades productivas de Argentina y la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, contar\u00e1 con las intervenciones del vicepresidente de ALADYR, Alejandro Sturniolo, quien subray\u00f3 que \u201cesta es una iniciativa que pretende estimular la participaci\u00f3n de todos los sectores para avanzar en las metas de agua y saneamiento en el pa\u00eds que son parte de los Objetivos de Desarrollo Sostenible promovidos por la ONU\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, desde Unilever estar\u00e1n presentando los compromisos de Clima y Naturaleza anunciados recientemente a nivel global. Los mismos &nbsp;contemplan llegar a la huella de carbono cero en todos sus productos para el a\u00f1o 2039, tener una cadena libre de deforestaci\u00f3n para 2023, implementar un C\u00f3digo de Agricultura Regenerativa y empoderar a una nueva generaci\u00f3n de peque\u00f1os productores para fomentar programas que protejan y restauren los bosques, el suelo y la biodiversidad. Tambi\u00e9n contemplan implementar programas de administraci\u00f3n del agua en 100 sitios ubicados en zonas con estr\u00e9s h\u00eddrico para el a\u00f1o 2030.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span class=\"has-inline-color has-very-dark-gray-color\">Desde la compa\u00f1\u00eda, a\u00f1adieron que, a trav\u00e9s de su Plan de Vida Sustentable, buscan minimizar el impacto ambiental originado por sus operaciones \u00a0haciendo m\u00e1s eficientes los procesos para reducir el consumo de agua, utilizando las \u00faltimas tecnolog\u00edas para el tratamiento de efluentes y fomentando el uso de energ\u00edas limpias para reducir las emisiones de di\u00f3xido de carbono. Adem\u00e1s, la compa\u00f1\u00eda contin\u00faa con su compromiso de enviar cero residuos a rellenos sanitarios.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0ALADYR y Futuro Sustentable continuar\u00e1n acercando a los l\u00edderes y principales referentes de la sostenibilidad \u00a0h\u00eddrica a la audiencia en general con este ciclo de entrevistas que busca crear conciencia sobre la importancia de integrar las tecnolog\u00edas de tratamiento y re\u00faso de agua y efluentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para participar solo debes inscribirte en este <a href=\"https:\/\/aladyr.net\/webinars\/compromisos-clima-naturaleza-y-agua\/\" target=\"_blank\" rel=\"noreferrer noopener\">link.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La compa\u00f1\u00eda concentra varias de las marcas m\u00e1s consumidas del mundo y tiene importantes objetivos de sustentabilidad que incluyen el re\u00faso de agua. Sobre esto y m\u00e1s se hablar\u00e1 en el ciclo de entrevistas interactivas \u201cL\u00edder H2O\u201d<\/p>\n","protected":false},"author":2873,"featured_media":17950,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[62],"tags":[2215],"class_list":["post-17949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-agua"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unilever explicar\u00e1 sus metas de compromiso ambiental para 2039 - Aladyr<\/title>\n<meta name=\"description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unilever explicar\u00e1 sus metas de compromiso ambiental para 2039 - Aladyr\" \/>\n<meta property=\"og:description\" content=\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/\" \/>\n<meta property=\"og:site_name\" content=\"Aladyr\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/asociacionaladyr\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-22T13:12:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-22T13:12:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/unilever.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"492\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:site\" content=\"@aladyr_asoc\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diego Ortu\u00c3\u00b1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\\\/\"},\"author\":{\"name\":\"Diego Ortu\u00c3\u00b1o\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\"},\"headline\":\"Unilever explicar\u00e1 sus metas de compromiso ambiental para 2039\",\"datePublished\":\"2020-10-22T13:12:08+00:00\",\"dateModified\":\"2020-10-22T13:12:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\\\/\"},\"wordCount\":616,\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/unilever.jpg\",\"keywords\":[\"agua\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/en\\\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\\\/\",\"name\":\"Unilever explicar\u00e1 sus metas de compromiso ambiental para 2039 - Aladyr\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/unilever.jpg\",\"datePublished\":\"2020-10-22T13:12:08+00:00\",\"dateModified\":\"2020-10-22T13:12:10+00:00\",\"description\":\"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aladyr.net\\\/en\\\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/unilever.jpg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/unilever.jpg\",\"width\":940,\"height\":492},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aladyr.net\\\/en\\\/homepage-2025\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unilever explicar\u00e1 sus metas de compromiso ambiental para 2039\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/aladyr.net\\\/en\\\/\",\"name\":\"Aladyr\",\"description\":\"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua\",\"publisher\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aladyr.net\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#organization\",\"name\":\"Aladyr\",\"url\":\"https:\\\/\\\/aladyr.net\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"contentUrl\":\"https:\\\/\\\/aladyr.net\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/Aladyr-Fallback.jpg\",\"width\":600,\"height\":400,\"caption\":\"Aladyr\"},\"image\":{\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/asociacionaladyr\\\/\",\"https:\\\/\\\/x.com\\\/aladyr_asoc\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/aladyr\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCeGIYolI-td4K6GiafV32rA\",\"https:\\\/\\\/www.instagram.com\\\/aladyr_asociacion\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aladyr.net\\\/en\\\/#\\\/schema\\\/person\\\/2e382449e6d4e26f7e2e41580a763f3f\",\"name\":\"Diego Ortu\u00c3\u00b1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g\",\"caption\":\"Diego Ortu\u00c3\u00b1o\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unilever explicar\u00e1 sus metas de compromiso ambiental para 2039 - Aladyr","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/","og_locale":"en_US","og_type":"article","og_title":"Unilever explicar\u00e1 sus metas de compromiso ambiental para 2039 - Aladyr","og_description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","og_url":"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/","og_site_name":"Aladyr","article_publisher":"https:\/\/www.facebook.com\/asociacionaladyr\/","article_published_time":"2020-10-22T13:12:08+00:00","article_modified_time":"2020-10-22T13:12:10+00:00","og_image":[{"width":940,"height":492,"url":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/unilever.jpg","type":"image\/jpeg"}],"author":"Diego Ortu\u00c3\u00b1o","twitter_card":"summary_large_image","twitter_creator":"@aladyr_asoc","twitter_site":"@aladyr_asoc","twitter_misc":{"Written by":"Diego Ortu\u00c3\u00b1o","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/#article","isPartOf":{"@id":"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/"},"author":{"name":"Diego Ortu\u00c3\u00b1o","@id":"https:\/\/aladyr.net\/en\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f"},"headline":"Unilever explicar\u00e1 sus metas de compromiso ambiental para 2039","datePublished":"2020-10-22T13:12:08+00:00","dateModified":"2020-10-22T13:12:10+00:00","mainEntityOfPage":{"@id":"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/"},"wordCount":616,"publisher":{"@id":"https:\/\/aladyr.net\/en\/#organization"},"image":{"@id":"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/unilever.jpg","keywords":["agua"],"articleSection":["Noticias"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/","url":"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/","name":"Unilever explicar\u00e1 sus metas de compromiso ambiental para 2039 - Aladyr","isPartOf":{"@id":"https:\/\/aladyr.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/#primaryimage"},"image":{"@id":"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/#primaryimage"},"thumbnailUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/unilever.jpg","datePublished":"2020-10-22T13:12:08+00:00","dateModified":"2020-10-22T13:12:10+00:00","description":"Bienvenido al Blog Aladyr. \u00ecinformate sobre las novedades del mundo del agua!","breadcrumb":{"@id":"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/#primaryimage","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/unilever.jpg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2020\/10\/unilever.jpg","width":940,"height":492},{"@type":"BreadcrumbList","@id":"https:\/\/aladyr.net\/en\/unilever-explicara-sus-metas-de-compromiso-ambiental-para-2039\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aladyr.net\/en\/homepage-2025\/"},{"@type":"ListItem","position":2,"name":"Unilever explicar\u00e1 sus metas de compromiso ambiental para 2039"}]},{"@type":"WebSite","@id":"https:\/\/aladyr.net\/en\/#website","url":"https:\/\/aladyr.net\/en\/","name":"Aladyr","description":"Asociaci\u00f3n Latinoamericana de Desalaci\u00f3n y Re\u00faso de Agua","publisher":{"@id":"https:\/\/aladyr.net\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aladyr.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/aladyr.net\/en\/#organization","name":"Aladyr","url":"https:\/\/aladyr.net\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aladyr.net\/en\/#\/schema\/logo\/image\/","url":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","contentUrl":"https:\/\/aladyr.net\/wp-content\/uploads\/2018\/05\/Aladyr-Fallback.jpg","width":600,"height":400,"caption":"Aladyr"},"image":{"@id":"https:\/\/aladyr.net\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/asociacionaladyr\/","https:\/\/x.com\/aladyr_asoc","https:\/\/www.linkedin.com\/company\/aladyr","https:\/\/www.youtube.com\/channel\/UCeGIYolI-td4K6GiafV32rA","https:\/\/www.instagram.com\/aladyr_asociacion\/"]},{"@type":"Person","@id":"https:\/\/aladyr.net\/en\/#\/schema\/person\/2e382449e6d4e26f7e2e41580a763f3f","name":"Diego Ortu\u00c3\u00b1o","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/baae4a0f26cdb223c9d210fba06e453585b65695bd6b2a08e13e00089e5d5984?s=96&r=g","caption":"Diego Ortu\u00c3\u00b1o"}}]}},"_links":{"self":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/posts\/17949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/users\/2873"}],"replies":[{"embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/comments?post=17949"}],"version-history":[{"count":0,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/posts\/17949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/media\/17950"}],"wp:attachment":[{"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/media?parent=17949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/categories?post=17949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aladyr.net\/en\/wp-json\/wp\/v2\/tags?post=17949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}